{"id":68421,"date":"2017-01-13T17:26:46","date_gmt":"2017-01-14T01:26:46","guid":{"rendered":"http:\/\/www.cetys.mx\/noticias\/?p=68421"},"modified":"2019-05-14T17:40:29","modified_gmt":"2019-05-15T00:40:29","slug":"sintesis-informativa-16-diciembre-2016","status":"publish","type":"sintesis","link":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-16-diciembre-2016\/","title":{"rendered":"S\u00edntesis Informativa de 16 de Diciembre de 2016"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cetys.mx\/userfiles\/sintesisDirectivos\/cetysenlosMedios.jpg\" alt=\"\" width=\"624\" height=\"78\" border=\"0\" \/><\/p>\n<p>Mexicali<\/p>\n<ul>\n<li>Monitor Econ\u00f3mico<br \/>\n<strong>Anunci\u00f3 CETYS Especialidad en Energ\u00edas Renovables para su Maestr\u00eda en Ingenier\u00eda<\/strong><br \/>\nSe dio a conocer el lanzamiento de la especializaci\u00f3n en Sustentabilidad y Energ\u00edas Renovables de la Maestr\u00eda en Ingenier\u00eda e Innovaci\u00f3n (MII) de CETYS Universidad.<br \/>\n<a href=\"https:\/\/monitoreconomico.org\/noticias\/2016\/dec\/15\/anuncio-cetys-especialidad-en-energias-renovables-para-su-maestria-en-ingeniria\/\">https:\/\/monitoreconomico.org\/noticias\/2016\/dec\/15\/anuncio-cetys-especialidad-en-energias-renovables-para-su-maestria-en-ingeniria\/<\/a><\/li>\n<\/ul>\n<ul>\n<li>La Voz de la Frontera<br \/>\n<strong>Ofrece CETYS especialidad en energ\u00edas renovables a los ingenieros<\/strong><br \/>\nEsta ma\u00f1ana en rueda de prensa, se dio a conocer el lanzamiento de la especializaci\u00f3n en Sustentabilidad y Energ\u00edas Renovables de la Maestr\u00eda en Ingenier\u00eda e Innovaci\u00f3n (MII) de CETYS Universidad.<br \/>\n<a href=\"https:\/\/www.lavozdelafrontera.com.mx\/mexicali\/ofrece-cetys-especialidad-en-energias-renovables-a-los-ingenieros\">https:\/\/www.lavozdelafrontera.com.mx\/mexicali\/ofrece-cetys-especialidad-en-energias-renovables-a-los-ingenieros<\/a><\/li>\n<\/ul>\n<ul>\n<li>El Mexicano<br \/>\n<strong>S\u00e1bado: M\u00e9xico y EU Taz\u00f3n de las Estrellasa<\/strong><br \/>\nLas selecciones de M\u00e9xico y Estados Unidos se declararon listo para el Taz\u00f3n de las Estrellas, mismo que se llevar\u00e1 a cabo este s\u00e1bado 17 de diciembre en el Estadio de Los Zorros del CETYS Campus Mexicali en punto de las 14:00 horas.<br \/>\n<a href=\"https:\/\/www.mxl.cetys.mx\/ci\/notasperiodico\/resultado.php?f=mn_151216_02b.jpg\">https:\/\/www.mxl.cetys.mx\/ci\/notasperiodico\/resultado.php?f=mn_151216_02b.jpg<\/a><\/li>\n<\/ul>\n<ul>\n<li>La Voz de la Frontera<br \/>\n<strong>EL DEPORTE Y SUS PROTAGONISTAS<\/strong><br \/>\nLas selecciones de M\u00e9xico y Estados Unidos se declararon listo para el Taz\u00f3n de las Estrellas, mismo que se llevar\u00e1 a cabo este s\u00e1bado 17 de diciembre en el Estadio de Los Zorros del CETYS Campus Mexicali en punto de las 14:00 horas.<br \/>\n<a href=\"https:\/\/www.mxl.cetys.mx\/ci\/notasperiodico\/resultado.php?f=vc_131216_03b.jpg\">https:\/\/www.mxl.cetys.mx\/ci\/notasperiodico\/resultado.php?f=vc_131216_03b.jpg<\/a><\/li>\n<\/ul>\n<ul>\n<li>Periodismo Negro<br \/>\n<strong>Integra CETYS Universidad Maestr\u00eda en Sustentabilidad y Energ\u00edas Renovables<\/strong><br \/>\nCon base en las necesidades que tienen la comunidad, la industria y \u00f3venes que buscan seguir su preparaci\u00f3n profesional, Cetys Universidad incorpor\u00f3 un programa de posgrado el cual se impartir\u00e1 en los salones de clase a partir de enero del 2017.<br \/>\n<a href=\"https:\/\/www.periodismonegro.mx\/2016\/12\/integra-cetys-universidad-maestria-en-sustentabilidad-y-energias-renovables\/\">https:\/\/www.periodismonegro.mx\/2016\/12\/integra-cetys-universidad-maestria-en-sustentabilidad-y-energias-renovables\/<\/a><\/li>\n<\/ul>\n<ul>\n<li>Monitor Econ\u00f3mico<br \/>\n<strong>Anunci\u00f3 CETYS Especialidad en Energ\u00edas Renovables para su Maestr\u00eda en Ingenier\u00eda<\/strong><br \/>\nCETYS Universidad campus Mexicali anunci\u00f3 el lanzamiento de la especializaci\u00f3n en Sustentabilidad y Energ\u00edas Renovables de la Maestr\u00eda en Ingenier\u00eda e Innovaci\u00f3n (MII).<br \/>\n<a href=\"https:\/\/www.facebook.com\/monitoreconomico.org\/photos\/a.268708589832389.62017.199098863460029\/1230819263621312\/?type=3&amp;theater\">https:\/\/www.facebook.com\/monitoreconomico.org\/photos\/a.268708589832389.62017.199098863460029\/1230819263621312\/?type=3&amp;theater<\/a><\/li>\n<\/ul>\n<ul>\n<li>La Cr\u00f3nica<br \/>\n<strong>Se espera una \u00e9pica edici\u00f3n<\/strong><br \/>\nLas selecciones de M\u00e9xico y Estados Unidos se declararon listo para el Taz\u00f3n de las Estrellas, mismo que se llevar\u00e1 a cabo este s\u00e1bado 17 de diciembre en el Estadio de Los Zorros del CETYS Campus Mexicali en punto de las 14:00 horas.<br \/>\n<a href=\"https:\/\/www.mxl.cetys.mx\/ci\/notasperiodico\/resultado.php?f=cn_151216_05b.jpg\">https:\/\/www.mxl.cetys.mx\/ci\/notasperiodico\/resultado.php?f=cn_151216_05b.jpg<\/a><\/li>\n<\/ul>\n<ul>\n<li>AGP Noticias<br \/>\n<strong>Taz\u00f3n de Las Estrellas el s\u00e1bado en Cetys Mexicali<\/strong><br \/>\nLas selecciones de M\u00e9xico y Estados Unidos se declararon listo para el Taz\u00f3n de las Estrellas, mismo que se llevar\u00e1 a cabo este s\u00e1bado 17 de diciembre en el Estadio de Los Zorros del CETYS Campus Mexicali en punto de las 14:00 horas.<br \/>\n<a href=\"https:\/\/agpnoticias.com\/news\/tazon-de-las-estrellas-el-sabado-en-cetys-mexicali\/\">https:\/\/agpnoticias.com\/news\/tazon-de-las-estrellas-el-sabado-en-cetys-mexicali\/<\/a><\/li>\n<\/ul>\n<ul>\n<li>Silbatazo<br \/>\n<strong>M\u00e9xico busca igual serie en Taz\u00f3n de las Estrellas<\/strong><br \/>\nCarlos Altamirano, entrenador en jefe del cuadro representativo de la Conferencia Premier de la Conedeip, mostr\u00f3 su confianza en que el equipo pueda igualar la serie en el Taz\u00f3n de las Estrellas donde enfrentan al combinado de la NCAA nivel 3 de los Estados Unidos.<br \/>\n<a href=\"https:\/\/www.sexenio.com.mx\/silbatazo\/articulo.php?id=56125\">https:\/\/www.sexenio.com.mx\/silbatazo\/articulo.php?id=56125<\/a><\/li>\n<\/ul>\n<ul>\n<li>20 minutos<br \/>\n<strong>Selecciones de M\u00e9xico y EUA listas para Taz\u00f3n de las Estrellas<\/strong><br \/>\nLas selecciones de M\u00e9xico y Estados Unidos se declararon listas para la s\u00e9ptima edici\u00f3n del Taz\u00f3n de las Estrellas, en duelo previsto para este s\u00e1bado en el Estadio de los Zorros de Cetys Universidad, Campus Mexicali.<br \/>\n<a href=\"https:\/\/www.20minutos.com.mx\/deportes\/noticia\/selecciones-de-mexico-y-eua-listas-para-tazon-de-las-estrellas-169527\/0\/\">https:\/\/www.20minutos.com.mx\/deportes\/noticia\/selecciones-de-mexico-y-eua-listas-para-tazon-de-las-estrellas-169527\/0\/<\/a><\/li>\n<\/ul>\n<ul>\n<li>La Afici\ufffdn<br \/>\n<strong>Buscar\u00e0 M\u00e8xico igualar Taz\u00f2n de las Estrellas ante EU<\/strong><br \/>\nEl entrenador del representativo mexicano, Carlos Altamirano, confi\u00f2 en el roster del equipo para igualar la serie del Taz\u00f2n de las Estrellas ante los Estados Unidos.<br \/>\n<a href=\"https:\/\/laaficion.milenio.com\/americano\/mexico-tazon_de_estellas-condeip-estados_unidos-mexicali-milenio-la_aficion_0_866313770.html\">https:\/\/laaficion.milenio.com\/americano\/mexico-tazon_de_estellas-condeip-estados_unidos-mexicali-milenio-la_aficion_0_866313770.html<\/a><\/li>\n<\/ul>\n<ul>\n<li>Radio F\ufffdrmula<br \/>\n<strong>Selecciones de M\u00e9xico y EU listas para Taz\u00f3n de las Estrellas<\/strong><br \/>\nEn rueda de prensa, Mario Dipp, director del Cetys Universidad Campus Mexicali, dio a conocer detalles de este evento deportivo, en el cual participar\u00e1 M\u00e9xico como selecci\u00f3n CONADEIP, y Estados Unidos, como equipo Estrellas y Rayas.<br \/>\n<a href=\"https:\/\/www.radioformula.com.mx\/notas.asp?Idn=648802&amp;idFC=2016\">https:\/\/www.radioformula.com.mx\/notas.asp?Idn=648802&amp;idFC=2016<\/a><\/li>\n<\/ul>\n<p>Tijuana<\/p>\n<ul>\n<li>Plural<br \/>\n<strong>Todo listo en Mexicali para el Taz\u00f3n de las estrellas<\/strong><br \/>\nTodo listo en Mexicali para el Taz\u00f3n de las estrellas , las selecciones de M\u00e9xico y Estados Unidos se declararon listas para la s\u00e9ptima edici\u00f3n del &#8220;Taz\u00f3n de las Estrellas&#8221;, mismo que se llevar\u00e1 a cabo este s\u00e1bado 17 de diciembre en el &#8220;Estadio de Los Zorros&#8221; de CETYS Universidad Campus Mexicali en punto de las 14:00 horas<br \/>\n<a href=\"https:\/\/www.plural.mx\/deportes\/listo-mexicali-tazon-las-estrellas\/\">https:\/\/www.plural.mx\/deportes\/listo-mexicali-tazon-las-estrellas\/<\/a><\/li>\n<\/ul>\n<ul>\n<li>20 Minutos<br \/>\n<strong>Selecciones de M\u00e9xico y EUA listas para Taz\u00f3n de las Estrellas <\/strong><br \/>\nLas selecciones de M\u00e9xico y Estados Unidos se declararon listas para la s\u00e9ptima edici\u00f3n del Taz\u00f3n de las Estrellas, en duelo previsto para este s\u00e1bado en el Estadio de los Zorros de Cetys Universidad, Campus Mexicali.<br \/>\n<a href=\"https:\/\/www.20minutos.com.mx\/deportes\/noticia\/selecciones-de-mexico-y-eua-listas-para-tazon-de-las-estrellas-169527\/0\/\">https:\/\/www.20minutos.com.mx\/deportes\/noticia\/selecciones-de-mexico-y-eua-listas-para-tazon-de-las-estrellas-169527\/0\/<\/a><\/li>\n<\/ul>\n<ul>\n<li>El Siglo<br \/>\n<strong>Listas, las selecciones <\/strong><br \/>\nEn rueda de prensa, Mario Dipp, director del Cetys Universidad Campus Mexicali, dio a conocer detalles de este evento deportivo, en el cual participar\u00e1 M\u00e9xico como selecci\u00f3n Conadeip, y Estados Unidos, como equipo Estrellas y Rayas.<br \/>\n<a href=\"https:\/\/www.elsiglodedurango.com.mx\/noticia\/705141.listas-las-selecciones.html\">https:\/\/www.elsiglodedurango.com.mx\/noticia\/705141.listas-las-selecciones.html<\/a><\/li>\n<\/ul>\n<ul>\n<li>Grupo F\ufffdrmula<br \/>\n<strong>Selecciones de M\u00e9xico y EU listas para Taz\u00f3n de las Estrellas<\/strong><br \/>\nEn rueda de prensa, Mario Dipp, director del Cetys Universidad Campus Mexicali, dio a conocer detalles de este evento deportivo, en el cual participar\u00e1 M\u00e9xico como selecci\u00f3n CONADEIP, y Estados Unidos, como equipo Estrellas y Rayas.<br \/>\n<a href=\"https:\/\/www.radioformula.com.mx\/notas.asp?Idn=648802&amp;idFC=2016\">https:\/\/www.radioformula.com.mx\/notas.asp?Idn=648802&amp;idFC=2016<\/a><\/li>\n<\/ul>\n<ul>\n<li>Diario Digital Baja California<br \/>\n<strong>Zorros Femenil se corona en la Liga Champagnat 2016<\/strong><br \/>\nZorros Femenil de la Preparatoria de CETYS Universidad Campus Tijuana apale\u00f3 a Jaguares de la Preparatoria Federal L\u00e1zaro C\u00e1rdenas por marcador de 52 puntos a 29, para llevarse una vez m\u00e1s un t\u00edtulo consecutivo de la Copa Champagnat que organiza a\u00f1o con a\u00f1o el Instituto M\u00e9xico.<br \/>\n<a href=\"https:\/\/www.periodicobajacalifornia.info\/index.php\/deportes\/item\/3191-zorros-femenil-se-corona-en-la-liga-champagnat-2016\">https:\/\/www.periodicobajacalifornia.info\/index.php\/deportes\/item\/3191-zorros-femenil-se-corona-en-la-liga-champagnat-2016<\/a><\/li>\n<\/ul>\n<ul>\n<li>El Mexicano<br \/>\n<strong>Ense\u00f1anza Matem\u00e1tica debe reinventarse<\/strong><br \/>\nCon el objetivo de conocer los retos y oportunidades a las que se enfrenta la ense\u00f1anza de las Matem\u00e1ticas ante las nuevas generaciones, se present\u00f3 el Dr. Sergio Pou Alber\u00fa, Acad\u00e9mico de la Maestr\u00eda en Educaci\u00f3n de CETYS Universidad, con la Conferencia &#8220;Matem\u00e1ticas: Claves para potenciar su ense\u00f1anza&#8221;.<br \/>\n<a href=\"https:\/\/www.mxl.cetys.mx\/ci\/notasperiodico\/resultado.php?f=matematicas_cetys.jpg\">https:\/\/www.mxl.cetys.mx\/ci\/notasperiodico\/resultado.php?f=matematicas_cetys.jpg<\/a><\/li>\n<\/ul>\n<ul>\n<li>Frontera<br \/>\n<strong>Estrellas iluminan el campo<\/strong><br \/>\nLa Comisi\u00f3n Nacional Deportiva Estudiantil de Instituciones Privadas (Conadeip) enfrentar\u00e1 ma\u00f1ana a Team Stars &amp; Stripes, en la s\u00e9ptima edici\u00f3n del Taz\u00f3n de las Estrellas.<br \/>\n<a href=\"https:\/\/www.mxl.cetys.mx\/ci\/notasperiodico\/resultado.php?f=estrellas_campocetys.jpg\">https:\/\/www.mxl.cetys.mx\/ci\/notasperiodico\/resultado.php?f=estrellas_campocetys.jpg<\/a><\/li>\n<\/ul>\n<ul>\n<li>Zeta<br \/>\n<strong>Jugadores de OEFA al Taz\u00f3n de Estrellas<\/strong><br \/>\nTodo est\u00e1 listo para que el s\u00e1bado 17 de diciembre a las 2:00 pm, se dispute la VII edici\u00f3n del Taz\u00f3n de las Estrellas, entre la selecci\u00f3n de Futbol Americano de M\u00e9xico y Estados Unidos, en el emparrillado del Cetys Campus Mexicali.<br \/>\n<a href=\"https:\/\/www.mxl.cetys.mx\/ci\/notasperiodico\/resultado.php?f=oefa_tazoncetys.jpg\">https:\/\/www.mxl.cetys.mx\/ci\/notasperiodico\/resultado.php?f=oefa_tazoncetys.jpg<\/a><\/li>\n<\/ul>\n<ul>\n<li>Conadeip<br \/>\n<strong>Todo listo para el VIII Taz\u00f3n de las Estrellas<\/strong><br \/>\nLas selecciones de M\u00e9xico y Estados Unidos se declararon listas para el Taz\u00f3n de las Estrellas, mismo que se llevar\u00e1 a cabo este s\u00e1bado 17 de diciembre en el Estadio de Cetys Universidad en punto de las 14:00 horas.<br \/>\n<a href=\"https:\/\/conadeipfba.org.mx\/tags\/tazon-de-estrellas\">https:\/\/conadeipfba.org.mx\/tags\/tazon-de-estrellas<\/a><\/li>\n<\/ul>\n<ul>\n<li>Monitor Econ\u00f3mico<br \/>\n<strong>Todo listo para el Taz\u00f3n de las Estrellas ma\u00f1ana en CETYS Mexicali<\/strong><br \/>\nLas selecciones de M\u00e9xico y Estados Unidos se declararon listas para la s\u00e9ptima edici\u00f3n del &#8220;Taz\u00f3n de las Estrellas&#8221;, mismo que se llevar\u00e1 a cabo este s\u00e1bado 17 de diciembre en el &#8220;Estadio de Los Zorros&#8221; de CETYS Universidad Campus Mexicali en punto de las 14:00 horas.<br \/>\n<a href=\"https:\/\/monitoreconomico.org\/media\/pdf\/edicion-digital\/2016\/12\/15\/16_diciembre_2016.pdf\">https:\/\/monitoreconomico.org\/media\/pdf\/edicion-digital\/2016\/12\/15\/16_diciembre_2016.pdf<\/a><\/li>\n<\/ul>\n<ul>\n<li>InfoBaja<br \/>\n<strong>Zorros Femenil es campe\u00f3n de Champagnat 2016<\/strong><br \/>\nZorros Femenil de la Preparatoria de CETYS Universidad Campus Tijuana apale\u00f3 a Jaguares de la Preparatoria Federal L\u00e1zaro C\u00e1rdenas por marcador de 52 puntos a 29, para llevarse una vez m\u00e1s un t\u00edtulo consecutivo de la Copa Champagnat que organiza a\u00f1o con a\u00f1o el Instituto M\u00e9xico.<br \/>\n<a href=\"https:\/\/infobaja.info\/universidades\/32589-zorros-femenil-es-campeon-de-champagnat-2016\">https:\/\/infobaja.info\/universidades\/32589-zorros-femenil-es-campeon-de-champagnat-2016<\/a><\/li>\n<\/ul>\n<p>Ensenada<\/p>\n<ul>\n<li>AGPNoticias<br \/>\n<strong>Taz\u00f3n de Las Estrellas el s\u00e1bado en Cetys Mexicali<\/strong><br \/>\nLas selecciones de M\u00e9xico y Estados Unidos se declararon listo para el Taz\u00f3n de las Estrellas, mismo que se llevar\u00e1 a cabo este s\u00e1bado 17 de diciembre en el Estadio de Los Zorros del CETYS Campus Mexicali en punto de las 14:00 horas. Este mi\u00e9rcoles en rueda de prensa se dieron a conocer los detalles de este magno evento deportivo en el cual participar\u00e1n la selecci\u00f3n de M\u00e9xico de la CONADEIP y l<br \/>\n<a href=\"https:\/\/agpnoticias.com\/news\/tazon-de-las-estrellas-el-sabado-en-cetys-mexicali\/\">https:\/\/agpnoticias.com\/news\/tazon-de-las-estrellas-el-sabado-en-cetys-mexicali\/<\/a><\/li>\n<\/ul>\n<ul>\n<li>4Vientos<br \/>\n<strong>&#8220;TRANSFORMANDO LA REALIDAD EDUCATIVA&#8221;, NUEVA PROPUESTA EDUCATIVA DE CETYS UNIVERSIDAD<\/strong><br \/>\nCon el objetivo de informar a la comunidad sobre la nueva propuesta acad\u00e9mica de CETYS Universidad, el mi\u00e9rcoles 14 de diciembre de 2016 se convoc\u00f3 a los medios locales a rueda de prensa presidida por el Dr. Alberto G\u00e1rate Rivera \ufffdVicerrector Acad\u00e9mico del Sistema CETYS Universidad\ufffd, la Dra. Cecilia Osuna Lever \ufffdDirectora del Colegio de Ciencias Sociales y Humanidades del CETYS\ufffd y la Mtra. Jessica<br \/>\n<a href=\"https:\/\/www.4vientos.net\/transformando-la-realidad-educativa-nuevo-doctorado-en-educacion\/\">https:\/\/www.4vientos.net\/transformando-la-realidad-educativa-nuevo-doctorado-en-educacion\/<\/a><\/li>\n<\/ul>\n<ul>\n<li>Frontera<br \/>\n<strong>Cetys tendr\u00e1 doctorado en educaci\u00f3n<\/strong><br \/>\nEl Sistema CETYS Universidad contar\u00e1 con el nuevo programa de Doctorado en Educaci\u00f3n, &#8220;Transformando la realidad educativa&#8221; en 2017, as\u00ed se anunci\u00f3 en una rueda de prensa por parte de la instituci\u00f3n.<br \/>\n<a href=\"https:\/\/www.frontera.info\/EdicionEnLinea\/Notas\/Noticias\/14122016\/1159412-Cetys-tendra-doctorado-en-educacion.html\">https:\/\/www.frontera.info\/EdicionEnLinea\/Notas\/Noticias\/14122016\/1159412-Cetys-tendra-doctorado-en-educacion.html<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Mexicali Monitor Econ\u00f3mico Anunci\u00f3 CETYS Especialidad en Energ\u00edas Renovables para su Maestr\u00eda en Ingenier\u00eda Se dio a conocer el lanzamiento de la&#8230;<\/p>\n","protected":false},"author":26,"featured_media":14504,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","categories":[130],"class_list":["post-68421","sintesis","type-sintesis","status-publish","has-post-thumbnail","hentry","category-sintesis-informativa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00edntesis Informativa de 16 de Diciembre de 2016 - CETYS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-16-diciembre-2016\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00edntesis Informativa de 16 de Diciembre de 2016 - CETYS\" \/>\n<meta property=\"og:description\" content=\"Mexicali Monitor Econ\u00f3mico Anunci\u00f3 CETYS Especialidad en Energ\u00edas Renovables para su Maestr\u00eda en Ingenier\u00eda Se dio a conocer el lanzamiento de la...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-16-diciembre-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"CETYS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cetysuniversidadmxl\/\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-15T00:40:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2016\/01\/sintesis_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"958\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cetysuni\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-16-diciembre-2016\\\/\",\"url\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-16-diciembre-2016\\\/\",\"name\":\"S\u00edntesis Informativa de 16 de Diciembre de 2016 - CETYS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-16-diciembre-2016\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-16-diciembre-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/sintesis_.jpg\",\"datePublished\":\"2017-01-14T01:26:46+00:00\",\"dateModified\":\"2019-05-15T00:40:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-16-diciembre-2016\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-16-diciembre-2016\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-16-diciembre-2016\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/sintesis_.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/sintesis_.jpg\",\"width\":958,\"height\":479},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-16-diciembre-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00edntesis\",\"item\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S\u00edntesis Informativa de 16 de Diciembre de 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/\",\"name\":\"CETYS\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00edntesis Informativa de 16 de Diciembre de 2016 - CETYS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-16-diciembre-2016\/","og_locale":"es_MX","og_type":"article","og_title":"S\u00edntesis Informativa de 16 de Diciembre de 2016 - CETYS","og_description":"Mexicali Monitor Econ\u00f3mico Anunci\u00f3 CETYS Especialidad en Energ\u00edas Renovables para su Maestr\u00eda en Ingenier\u00eda Se dio a conocer el lanzamiento de la...","og_url":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-16-diciembre-2016\/","og_site_name":"CETYS","article_publisher":"https:\/\/www.facebook.com\/cetysuniversidadmxl\/","article_modified_time":"2019-05-15T00:40:29+00:00","og_image":[{"width":958,"height":479,"url":"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2016\/01\/sintesis_.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@cetysuni","twitter_misc":{"Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-16-diciembre-2016\/","url":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-16-diciembre-2016\/","name":"S\u00edntesis Informativa de 16 de Diciembre de 2016 - CETYS","isPartOf":{"@id":"https:\/\/www.cetys.mx\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-16-diciembre-2016\/#primaryimage"},"image":{"@id":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-16-diciembre-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2016\/01\/sintesis_.jpg","datePublished":"2017-01-14T01:26:46+00:00","dateModified":"2019-05-15T00:40:29+00:00","breadcrumb":{"@id":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-16-diciembre-2016\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-16-diciembre-2016\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-16-diciembre-2016\/#primaryimage","url":"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2016\/01\/sintesis_.jpg","contentUrl":"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2016\/01\/sintesis_.jpg","width":958,"height":479},{"@type":"BreadcrumbList","@id":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-16-diciembre-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cetys.mx\/noticias\/"},{"@type":"ListItem","position":2,"name":"S\u00edntesis","item":"https:\/\/www.cetys.mx\/noticias\/sintesis\/"},{"@type":"ListItem","position":3,"name":"S\u00edntesis Informativa de 16 de Diciembre de 2016"}]},{"@type":"WebSite","@id":"https:\/\/www.cetys.mx\/noticias\/#website","url":"https:\/\/www.cetys.mx\/noticias\/","name":"CETYS","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cetys.mx\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/sintesis\/68421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/sintesis"}],"about":[{"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/types\/sintesis"}],"author":[{"embeddable":true,"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/comments?post=68421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/media\/14504"}],"wp:attachment":[{"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/media?parent=68421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/categories?post=68421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}