{"id":67361,"date":"2016-11-17T09:39:51","date_gmt":"2016-11-17T17:39:51","guid":{"rendered":"http:\/\/www.cetys.mx\/noticias\/?p=67361"},"modified":"2019-05-14T17:40:41","modified_gmt":"2019-05-15T00:40:41","slug":"sintesis-informativa-07-noviembre-2016","status":"publish","type":"sintesis","link":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-07-noviembre-2016\/","title":{"rendered":"S\u00edntesis Informativa de 07 de Noviembre de 2016"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cetys.mx\/userfiles\/sintesisDirectivos\/cetysenlosMedios.jpg\" alt=\"\" width=\"624\" height=\"78\" border=\"0\" \/><\/p>\n<p>Mexicali<\/p>\n<ul>\n<li>La Cr\u00f3nica<br \/>\n<strong>Panteras y Borrgos van por el t\u00edtulo<\/strong><br \/>\nEn el encuentro de Panteras ante Zorros, los del CETYS comenzaron imponi\u00e9ndose 10-6, pero vinieron las reacciones del contrario d\u00e1ndoles la vuelta 21-15.<br \/>\n<a href=\"https:\/\/www.lacronica.com\/EdicionEnLinea\/Notas\/DeportesLocal\/04112016\/1146222-Panteras-y-Borregos-van-por-el-titulo.html\">https:\/\/www.lacronica.com\/EdicionEnLinea\/Notas\/DeportesLocal\/04112016\/1146222-Panteras-y-Borregos-van-por-el-titulo.html<\/a><\/li>\n<\/ul>\n<ul>\n<li>24 Horas<br \/>\n<strong>Mexicali ser\u00e1 sede del Taz\u00f3n de las Estrellas<\/strong><br \/>\nEl director del Centro de Ense\u00f1anza T\u00e9cnica y Superior (Cetys) Universidad campus Mexicali, Mario Dipp N\u00fa\u00f1ez, inform\u00f3 que el tradicional partido entre los dos colectivos que agrupan a los jugadores m\u00e1s representativos se llevar\u00e1 a cabo el 17 de diciembre.<br \/>\n<a href=\"https:\/\/www.24-horas.mx\/tazon-de-las-estrellas-sera-en-baja-california\/\">https:\/\/www.24-horas.mx\/tazon-de-las-estrellas-sera-en-baja-california\/<\/a><\/li>\n<\/ul>\n<ul>\n<li>El Mexicano<br \/>\n<strong>Crean bachilleres del Cetys 34 proyectos emprendedores<\/strong><br \/>\nUn total de 34 empresas juveniles participaron en la Expo Emprendedor Impulsa 2016, un evento organizado por los docentes de la asignatura Desarrollo Emprendedor Comunitario del Cetys Universidad en el que los alumnos de 5to semestre tuvieron que crear, desarrollar, producir y vender un producto o servicio.<br \/>\n<a href=\"https:\/\/www.el-mexicano.com.mx\/informacion\/noticias\/1\/3\/estatal\/2016\/11\/06\/999610\/crean-bachilleres-del-cetys-34-proyectos-emprendedores\">https:\/\/www.el-mexicano.com.mx\/informacion\/noticias\/1\/3\/estatal\/2016\/11\/06\/999610\/crean-bachilleres-del-cetys-34-proyectos-emprendedores<\/a><\/li>\n<\/ul>\n<ul>\n<li>El Siglo de Durango<br \/>\n<strong>Baja California albergar\u00e1 Taz\u00f3n de las Estrellas 2016<\/strong><br \/>\nEl Taz\u00f3n de las Estrellas, encuentro de futbol americano que confronta cada a\u00f1o a los representativos de M\u00e9xico y Estados Unidos, retornar\u00e1 a Baja California y tendr\u00e1 como escenario esta ciudad.<br \/>\n<a href=\"https:\/\/www.elsiglodedurango.com.mx\/noticia\/696906.en-corto.html\">https:\/\/www.elsiglodedurango.com.mx\/noticia\/696906.en-corto.html<\/a><\/li>\n<\/ul>\n<ul>\n<li>La Voz de la Frontera<br \/>\n<strong>Zorros Cetys Mexicali a la final en juvenil<\/strong><br \/>\nZorros Cetys Mexicali clasific\u00f3 a la gran final en la categor\u00eda Juvenil de la Organizaci\u00f3n Estudiantil de Futbol Americano (OEFA) al imponerse la tarde de este s\u00e1bado en dram\u00e1tico encuentro 21-19 a los Monaguillos del Instituto Salvatierra.<br \/>\n<a href=\"https:\/\/www.lavozdelafrontera.com.mx\/deporte-local\/zorros-cetys-mexicali-a-la-final-en-juvenil\">https:\/\/www.lavozdelafrontera.com.mx\/deporte-local\/zorros-cetys-mexicali-a-la-final-en-juvenil<\/a><\/li>\n<\/ul>\n<ul>\n<li>Mexicali Sport<br \/>\n<strong>Esperan gran espect\u00e1culo en el Taz\u00f3n de las Estrellas<\/strong><br \/>\nCetys Universidad de declara listo para el Taz\u00f3n de las Estrellas, magno evento de futbol americano que se llevar\u00e1 el s\u00e1bado 17 de diciembre en el renovado estadio &#8220;guarida&#8221; del Zorro del Centro de Ense\u00f1anza T\u00e9cnica y Superior.<br \/>\n<a href=\"https:\/\/mexicalisport.com\/esperan-gran-espectaculo-en-el-tazon-de-las-estrellas\/\">https:\/\/mexicalisport.com\/esperan-gran-espectaculo-en-el-tazon-de-las-estrellas\/<\/a><\/li>\n<\/ul>\n<ul>\n<li>Conadeip FBA<br \/>\n<strong>M\u00e9xico y Estados unidos se enfrentar\u00e1n en el VIII Taz\u00f3n de las Estrellas<\/strong><br \/>\nM\u00e1s de 2 mil personas se esperan para el gran evento deportivo de fin de a\u00f1o, el Taz\u00f3n de las Estrellas en Baja 2016, el cual se llevar\u00e1 a cabo en CETYS Universidad Campus Mexicali el pr\u00f3ximo 17 de diciembre en el estadio de Zorros Mexicali.<br \/>\n<a href=\"https:\/\/www.conadeipfba.org.mx\/node\/11836\">https:\/\/www.conadeipfba.org.mx\/node\/11836<\/a><\/li>\n<\/ul>\n<ul>\n<li>Notimex<br \/>\n<strong>CETYS Mexicali renueva estadio para Taz\u00f3n de Estrellas<\/strong><br \/>\nLas instalaciones del CETYS ser\u00e1 nuevamente sede del Taz\u00f3n de Estrellas del futbol americano estudiantil, que este a\u00f1o se realizar\u00e1 en el renovado Estadio de los Zorros Campus Mexicali, el pr\u00f3ximo 17 de octubre.<br \/>\n<a href=\"https:\/\/www.notimex.gob.mx\/notaLibre\/523317\">https:\/\/www.notimex.gob.mx\/notaLibre\/523317<\/a><\/li>\n<\/ul>\n<ul>\n<li>20 minutos<br \/>\n<strong>Baja California albergar\u00e1 Taz\u00f3n de las Estrellas 2016<\/strong><br \/>\nEl Taz\u00f3n de las Estrellas, encuentro de futbol americano que confronta cada a\u00f1o a los representativos de M\u00e9xico y Estados Unidos, retornar\u00e1 a Baja California y tendr\u00e1 como escenario esta ciudad.<br \/>\n<a href=\"https:\/\/www.20minutos.com.mx\/deportes\/noticia\/baja-california-albergara-tazon-de-las-estrellas-2016-154791\/0\/\">https:\/\/www.20minutos.com.mx\/deportes\/noticia\/baja-california-albergara-tazon-de-las-estrellas-2016-154791\/0\/<\/a><\/li>\n<\/ul>\n<ul>\n<li>Independiente<br \/>\n<strong>Baja California albergar\u00e1 Taz\u00f3n de las Estrellas 2016<\/strong><br \/>\nEl Taz\u00f3n de las Estrellas, encuentro de futbol americano que confronta cada a\u00f1o a los representativos de M\u00e9xico y Estados Unidos, retornar\u00e1 a Baja California y tendr\u00e1 como escenario Mexicali.<br \/>\n<a href=\"https:\/\/www.elindependientedehidalgo.com.mx\/baja-california-albergara-tazon-las-estrellas-2016\/\">https:\/\/www.elindependientedehidalgo.com.mx\/baja-california-albergara-tazon-las-estrellas-2016\/<\/a><\/li>\n<\/ul>\n<ul>\n<li>Terra Noticias<br \/>\n<strong>Baja California albergar\u00e1 Taz\u00f3n de las Estrellas 2016<\/strong><br \/>\nEl Taz\u00f3n de las Estrellas, encuentro de futbol americano que confronta cada a\u00f1o a los representativos de M\u00e9xico y Estados Unidos, retornar\u00e1 a Baja California y tendr\u00e1 como escenario esta ciudad.<br \/>\n<a href=\"https:\/\/deportes.terra.com.mx\/baja-california-albergara-tazon-de-las-estrellas-2016,ccfe600105f2c45421340f9a9f5abfff4vpi0f75.html\">https:\/\/deportes.terra.com.mx\/baja-california-albergara-tazon-de-las-estrellas-2016,ccfe600105f2c45421340f9a9f5abfff4vpi0f75.html<\/a><\/li>\n<\/ul>\n<p>Tijuana<\/p>\n<ul>\n<li>Infobaja<br \/>\n<strong>Regresa Taz\u00f3n a CETYS Universidad<\/strong><br \/>\nCETYS Universidad ser\u00e1 nuevamente sede del magno evento deportivo &#8220;Taz\u00f3n de Estrellas&#8221;, ahora en su edici\u00f3n 2016, a realizarse en el Estadio de los Zorros del Campus Mexicali el pr\u00f3ximo s\u00e1bado 17 de diciembre y cuya venta de boletos iniciar\u00e1 a partir de este lunes 7 de noviembre.<br \/>\n<a href=\"https:\/\/infobaja.info\/universidades\/32007-regresa-tazon-a-cetys-universidad\">https:\/\/infobaja.info\/universidades\/32007-regresa-tazon-a-cetys-universidad<\/a><\/li>\n<\/ul>\n<ul>\n<li>S\u00edntesis<br \/>\n<strong>CETYS se alista para albergar el Taz\u00f3n de Estrellas <\/strong><br \/>\nCETYS Universidad ser\u00e1 nuevamente sede del magno evento deportivo &#8220;Taz\u00f3n de Estrellas&#8221;, ahora en su edici\u00f3n 2016, a realizarse en el Estadio Zorro de Mexicali el pr\u00f3ximo s\u00e1bado 17 de diciembre, cuya venta de boletos iniciar\u00e1 a partir de este lunes 7 de noviembre.<br \/>\n<a href=\"https:\/\/stmedia.net\/noticias\/deportes\/mexicali-se-alista-para-albergar-el-tazon-estrellas#.WCC4iC3hC70\">https:\/\/stmedia.net\/noticias\/deportes\/mexicali-se-alista-para-albergar-el-tazon-estrellas#.WCC4iC3hC70<\/a><\/li>\n<\/ul>\n<ul>\n<li>El Mexicano<br \/>\n<strong>Disputar\u00e1n el VIII Taz\u00f3n de las Estrellas<\/strong><br \/>\nEl pr\u00f3ximo 17 de diciembre a las 14:00 horas ser\u00e1 realizada la octava edici\u00f3n del Taz\u00f3n de las Estrellas, enfrentamiento de f\u00fatbol americano colegial que por segundo a\u00f1o consecutivo tendr\u00e1 lugar en suelo bajacaliforniano, ya que el Estadio del Cetys Universidad campus Mexicali fungir\u00e1 como sede para el evento.<br \/>\n<a href=\"https:\/\/www.el-mexicano.com.mx\/informacion\/noticias\/1\/5\/deportes\/2016\/11\/04\/999443\/disputaran-en-mexicali-viii-tazon-de-las-estrellas\">https:\/\/www.el-mexicano.com.mx\/informacion\/noticias\/1\/5\/deportes\/2016\/11\/04\/999443\/disputaran-en-mexicali-viii-tazon-de-las-estrellas<\/a><\/li>\n<\/ul>\n<ul>\n<li>24 horas<br \/>\n<strong>Mexicali ser\u00e1 sede del Taz\u00f3n de las Estrellas<\/strong><br \/>\nLa decisi\u00f3n de Global Football de hacerlo en Baja California fue debido a la excelente organizaci\u00f3n y \u00e9xito que tuvo el encuentro entre los seleccionados de la NCAA Divisi\u00f3n III y CONADEIP en 2015.<br \/>\n<a href=\"https:\/\/www.24-horas.mx\/tazon-de-las-estrellas-sera-en-baja-california\/\">https:\/\/www.24-horas.mx\/tazon-de-las-estrellas-sera-en-baja-california\/<\/a><\/li>\n<\/ul>\n<ul>\n<li>Uniradioinforma.com<br \/>\n<strong>Baja California albergar\u00e1 Taz\u00f3n de las Estrellas 2016<\/strong><br \/>\nEl Taz\u00f3n de las Estrellas, encuentro de f\u00fatbol americano que confronta cada a\u00f1o a los representativos de M\u00e9xico y Estados Unidos, retornar\u00e1 a Baja California y tendr\u00e1 como escenario a CETYS Mexicali.<br \/>\n<a href=\"https:\/\/www.uniradioinforma.com\/noticias\/deportes\/446478\/baja-california-albergara-tazon-de-las-estrellas-2016.html\">https:\/\/www.uniradioinforma.com\/noticias\/deportes\/446478\/baja-california-albergara-tazon-de-las-estrellas-2016.html<\/a><\/li>\n<\/ul>\n<ul>\n<li>Tijuana Informativo<br \/>\n<strong>Regresar\u00e1 Tazon de Estrellas a CETYS Universidad<\/strong><br \/>\nCETYS Universidad ser\u00e1 nuevamente sede del magno evento deportivo &#8220;Taz\u00f3n de Estrellas&#8221;, ahora en su edici\u00f3n 2016, a realizarse en el Estadio de los Zorros del Campus Mexicali el pr\u00f3ximo s\u00e1bado 17 de diciembre y cuya venta de boletos iniciar\u00e1 a partir de este lunes 7 de noviembre.<br \/>\n<a href=\"https:\/\/www.tijuanainformativo.info\/index.php\/noticias-de-tijuana\/item\/48932-regresara-tazon-de-estrellas-a-cetys-universidad\">https:\/\/www.tijuanainformativo.info\/index.php\/noticias-de-tijuana\/item\/48932-regresara-tazon-de-estrellas-a-cetys-universidad<\/a><\/li>\n<\/ul>\n<ul>\n<li>S\u00edntesis<br \/>\n<strong>Taz\u00f3n Baja Juvenil XXII est\u00e1 definido <\/strong><br \/>\nZorros Mexicali y Zorros Tijuana tomar\u00e1n parte del Taz\u00f3n Baja Juvenil XXII, tras ganar sus respectivos encuentros de semifinales de la Organizaci\u00f3n Estudiantil de F\u00fatbol Americano de Baja California (OEFA).<br \/>\n<a href=\"https:\/\/stmedia.net\/noticias\/deportes\/tazon-baja-juvenil-xxii-esta-definido#.WCC4XS3hC70\">https:\/\/stmedia.net\/noticias\/deportes\/tazon-baja-juvenil-xxii-esta-definido#.WCC4XS3hC70<\/a><\/li>\n<\/ul>\n<ul>\n<li>El Sol de Tijuana<br \/>\n<strong>Gana Zorros semifinal a Jaguares en OEFA<\/strong><br \/>\nZorros, de Tijuana, ganaron su partido de semifinales de la categor\u00eda Juvenil &#8220;A&#8221; contra Jaguares por marcador de 14-6 para lograr su pase al XXII Taz\u00f3n de la Organizaci\u00f3n Estudiantil de F\u00fatbol Americano de Baja California (OEFA).<br \/>\n<a href=\"https:\/\/www.oem.com.mx\/elsoldetijuana\/notas\/n4319568.htm\">https:\/\/www.oem.com.mx\/elsoldetijuana\/notas\/n4319568.htm<\/a><\/li>\n<\/ul>\n<ul>\n<li>PSN<br \/>\n<strong>Catedr\u00e1ticos de Estados Unidos y Canad\u00e1 impartir\u00e1n clases a estudiantes del Cetys Universidad<\/strong><br \/>\nContando con la c\u00e1tedra de 14 docentes de CityU provenientes de Estados Unidos y Canad\u00e1, alrededor de 211 estudiantes de los programas de Doble Grado del Sistema CETYS Universidad pudieron vivir la experiencia en los campus Mexicali, Tijuana, y por primera ocasi\u00f3n tambi\u00e9n, en el campus Internacional de Ensenada.<br \/>\n<a href=\"https:\/\/psn.si\/catedraticos-estados-unidos-canada-impartiran-clases-a-estudiantes-del-cetys-universidad\/2016\/11\/\">https:\/\/psn.si\/catedraticos-estados-unidos-canada-impartiran-clases-a-estudiantes-del-cetys-universidad\/2016\/11\/<\/a><\/li>\n<\/ul>\n<ul>\n<li>Campus Milenio<br \/>\n<strong>Catedr\u00e1ticos de EU y Canad\u00e1 impartir\u00e1n clases a alumnos de doble grado en el Cetys<\/strong><br \/>\nContando con la c\u00e1tedra de 14 docentes de CityU provenientes de Estados Unidos y Canad\u00e1, alrededor de 211 estudiantes de los programas de Doble Grado del Sistema CETYS Universidad pudieron vivir la experiencia en los campus Mexicali, Tijuana, y por primera ocasi\u00f3n tambi\u00e9n, en el campus Internacional de Ensenada.<br \/>\n<a href=\"https:\/\/campusmilenio.mx\/index.php?option=com_k2&amp;view=item&amp;id=5157:catedraticos-de-eu-y-canada-impartiran-clases-a-alumnos-de-doble-grado-en-el-cetys&amp;Itemid=256\">https:\/\/campusmilenio.mx\/index.php?option=com_k2&amp;view=item&amp;id=5157:catedraticos-de-eu-y-canada-impartiran-clases-a-alumnos-de-doble-grado-en-el-cetys&amp;Itemid=256<\/a><\/li>\n<\/ul>\n<ul>\n<li>El Mexicano<br \/>\n<strong>Catedr\u00e1ticos extranjeros dar\u00e1n clases en el CETYS <\/strong><br \/>\nContando con la c\u00e1te- dra de 14 docentes de CityU prove- nientes de Estados Unidos y Canad\u00e1, alrededor de 211 estudiantes de los programas de Doble Grado del Sis- tema Cetys-Universidad podr\u00e1n vivir la experiencia en los campus Mexi- cali, Tijuana.<br \/>\n<a href=\"https:\/\/ed.el-mexicano.com.mx\/impreso\/Tijuana\/110616\/06-11-2016_TIJ_02A.pdf\">https:\/\/ed.el-mexicano.com.mx\/impreso\/Tijuana\/110616\/06-11-2016_TIJ_02A.pdf<\/a><\/li>\n<\/ul>\n<ul>\n<li>Infobaja<br \/>\n<strong>Los millennials al ataque<\/strong><br \/>\nEl viernes pasado di una conferencia en el simposio CIAN, en donde el 95% de los asistentes eran &#8220;Millennials&#8221;. Para poder entenderlos y adecuar mi mensaje sobre innovaci\u00f3n y emprendimiento, me tuve que dar a la tarea de estudiar a profundidad a esta generaci\u00f3n nacida entre 1980 y 2000.<br \/>\n<a href=\"https:\/\/www.infobaja.info\/columnas\/48-el-alquimista\/31999-los-millennials-al-ataque\">https:\/\/www.infobaja.info\/columnas\/48-el-alquimista\/31999-los-millennials-al-ataque<\/a><\/li>\n<\/ul>\n<ul>\n<li>Frontera<br \/>\n<strong>Suman en BC 112 casos de acoso escolar<\/strong><br \/>\nEs m\u00e1s \u00e1lgido en la secundaria y se reduce en la preparatoria, sin embargo los estudios de Cetys Universidad en Tijuana, muestran algunas diferencias en este municipio.<br \/>\n<a href=\"https:\/\/www.frontera.info\/EdicionEnLinea\/Notas\/Noticias\/07112016\/1147794-Suman-en-BC-112-casos-de-acoso-escolar.html\">https:\/\/www.frontera.info\/EdicionEnLinea\/Notas\/Noticias\/07112016\/1147794-Suman-en-BC-112-casos-de-acoso-escolar.html<\/a><\/li>\n<\/ul>\n<ul>\n<li>Tackleo<br \/>\n<strong>Gana Zorros Tijuana semifinal sobre Jaguares en juvenil A de OEFA<\/strong><br \/>\nZorros, de Tijuana, ganaron su partido de semifinales de la categor\u00eda Juvenil &#8220;A&#8221; contra Jaguares por marcador de 14-6 el s\u00e1bado 5 de noviembre para lograr su pase al XXII Taz\u00f3n de la Organizaci\u00f3n Estudiantil de F\u00fatbol Americano de Baja California (OEFA).<br \/>\n<a href=\"https:\/\/www.tackleo.com\/index.php?option=com_content&amp;view=article&amp;id=60572%3Agana-zorros-tijuana-semifinal-sobre-jaguares-en-juvneil-a-de-oefa&amp;catid=2039%3Aoefa&amp;Itemid=87\">https:\/\/www.tackleo.com\/index.php?option=com_content&amp;view=article&amp;id=60572%3Agana-zorros-tijuana-semifinal-sobre-jaguares-en-juvneil-a-de-oefa&amp;catid=2039%3Aoefa&amp;Itemid=87<\/a><\/li>\n<\/ul>\n<ul>\n<li>El Tijuanense<br \/>\n<strong>Tendr\u00e1n Cetys Mexicali y Tijuana cita para el XXI Taz\u00f3n Juvenil &#8220;A&#8221;<\/strong><br \/>\nLos representantes del campus Mexicali y Tijuana del Centro de Ense\u00f1anza T\u00e9cnica y Superior (Cetys) tomar\u00e1n parte del XXII Taz\u00f3n Juvenil &#8220;A&#8221; tras ganar sus respectivos encuentros de semifinales de la Organizaci\u00f3n Estudiantil de F\u00fatbol Americano de Baja California (OEFA).<br \/>\n<a href=\"https:\/\/www.mxl.cetys.mx\/sci1\/Zorros,%20de%20Tijuana,%20ganaron%20su%20partido%20de%20semifinales%20de%20la%20categor%EF%BF%BDa%20Juvenil\">Zorros, de Tijuana, ganaron su partido de semifinales de la categor\ufffda Juvenil &#8220;A&#8221; contra Jaguares por marcador de 14-6 el s\ufffdbado 5 de noviembre para lograr su pase al XXII Taz\ufffdn de la Organizaci\ufffdn Estudiantil de F\ufffdtbol Americano de Baja California (OEFA).<\/a><\/li>\n<\/ul>\n<ul>\n<li>El Sol de Tijuana<br \/>\n<strong>Se repetir\u00e1 &#8220;Taz\u00f3n de las Estrellas&#8221;<\/strong><br \/>\nEl encuentro de f\u00fatbol americano colegial m\u00e1s iportante de Norteam\u00e9rica se jugar\u00e1 nuevamente en Baja California, pero ahora en Campus Mexicali.<br \/>\n<a href=\"https:\/\/www.mxl.cetys.mx\/ci\/notasperiodico\/resultado.php?f=cetys_tazonelsol2016.jpg\">https:\/\/www.mxl.cetys.mx\/ci\/notasperiodico\/resultado.php?f=cetys_tazonelsol2016.jpg<\/a><\/li>\n<\/ul>\n<p>Ensenada<\/p>\n<ul>\n<li>El Vig\u00eda<br \/>\n<strong>Impartir\u00e1n c\u00e1tedra docentes extranjeros<\/strong><br \/>\nContando con la c\u00e1tedra de 14 docentes de CityU provenientes de Estados Unidos y Canad\u00e1, alrededor de 211 estudiantes de los programas de Doble Grado del Sistema Cetys Universidad pudieron vivir la experiencia en los campus Mexicali, Tijuana, y por primera ocasi\u00f3n tambi\u00e9n, en el campus Internacional de Ensenada.<br \/>\n<a href=\"https:\/\/www.elvigia.net\/general\/2016\/11\/5\/impartiran-catedra-docentes-extranjeros-253333.html\">https:\/\/www.elvigia.net\/general\/2016\/11\/5\/impartiran-catedra-docentes-extranjeros-253333.html<\/a><\/li>\n<\/ul>\n<ul>\n<li>El Vig\u00eda<br \/>\n<strong>Gana Princess a Zorros Femenil<\/strong><br \/>\nPrincess de Maneadero derrot\u00f3 44-20 a Zorros Femenil de Cetys Universidad en juego de la categor\u00eda Intermedia, programado por la Liga Municipal de Baloncesto de Ensenada.<br \/>\n<a href=\"https:\/\/www.elvigia.net\/deportes\/baloncesto\/2016\/11\/6\/gana-princess-zorros-femenil-254425.html\">https:\/\/www.elvigia.net\/deportes\/baloncesto\/2016\/11\/6\/gana-princess-zorros-femenil-254425.html<\/a><\/li>\n<\/ul>\n<ul>\n<li>RadaNoticias<br \/>\n<strong>CATEDR\u00c1TICOS INTERNACIONALES IMPARTIR\u00c1N CLASES DE CETYS<\/strong><br \/>\nContando con la c\u00e1tedra de 14 docentes de CityU provenientes de Estados Unidos y Canad\u00e1, alrededor de 211 estudiantes de los programas de Doble Grado del Sistema Cetys Universidad pudieron vivir la experiencia en los campus Mexicali, Tijuana, y por primera ocasi\u00f3n tambi\u00e9n, en el campus Internacional de Ensenada.<br \/>\n<a href=\"https:\/\/radanoticias.info\/catedraticos-internacionales-impartiran-clases-de-cetys\/\">https:\/\/radanoticias.info\/catedraticos-internacionales-impartiran-clases-de-cetys\/<\/a><\/li>\n<\/ul>\n<ul>\n<li>Ensenada.net<br \/>\n<strong>C\u00e1tedra de doble grado CETYS, ahora en Ensenada <\/strong><br \/>\nContando con la c\u00e1tedra de 14 docentes de CityU provenientes de Estados Unidos y Canad\u00e1, alrededor de 211 estudiantes de los programas de Doble Grado del Sistema Cetys Universidad pudieron vivir la experiencia en los campus Mexicali, Tijuana, y por primera ocasi\u00f3n tambi\u00e9n, en el campus Internacional de Ensenada.<br \/>\n<a href=\"https:\/\/ensenada.net\/noticias\/nota.php?id=47030\">https:\/\/ensenada.net\/noticias\/nota.php?id=47030<\/a><\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cetys.mx\/userfiles\/sintesisDirectivos\/notasdeEducacion.jpg\" alt=\"\" width=\"624\" height=\"78\" border=\"0\" \/><\/p>\n<p>Tijuana<\/p>\n<ul>\n<li>Business Conexion<br \/>\n<strong>55 Aniversario CETYS Universidad<\/strong><br \/>\nEl pasado 19 de septiembre CETYS Universidad cumpli\u00f3 su 55 Aniversario, los festejos fueron encabezados por el Dr. Fernando Le\u00f3n Garc\u00eda, Rector del Sistema CETYS Universidad.<br \/>\n<a href=\"https:\/\/www.mxl.cetys.mx\/ci\/notasperiodico\/resultado.php?f=cetys_aniv55businessconx.jpg\">https:\/\/www.mxl.cetys.mx\/ci\/notasperiodico\/resultado.php?f=cetys_aniv55businessconx.jpg<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Mexicali La Cr\u00f3nica Panteras y Borrgos van por el t\u00edtulo En el encuentro de Panteras ante Zorros, los del CETYS comenzaron imponi\u00e9ndose&#8230;<\/p>\n","protected":false},"author":26,"featured_media":14504,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","categories":[130],"class_list":["post-67361","sintesis","type-sintesis","status-publish","has-post-thumbnail","hentry","category-sintesis-informativa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00edntesis Informativa de 07 de Noviembre de 2016 - CETYS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-07-noviembre-2016\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00edntesis Informativa de 07 de Noviembre de 2016 - CETYS\" \/>\n<meta property=\"og:description\" content=\"Mexicali La Cr\u00f3nica Panteras y Borrgos van por el t\u00edtulo En el encuentro de Panteras ante Zorros, los del CETYS comenzaron imponi\u00e9ndose...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-07-noviembre-2016\/\" \/>\n<meta property=\"og:site_name\" content=\"CETYS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cetysuniversidadmxl\/\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-15T00:40:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2016\/01\/sintesis_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"958\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cetysuni\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-07-noviembre-2016\\\/\",\"url\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-07-noviembre-2016\\\/\",\"name\":\"S\u00edntesis Informativa de 07 de Noviembre de 2016 - CETYS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-07-noviembre-2016\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-07-noviembre-2016\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/sintesis_.jpg\",\"datePublished\":\"2016-11-17T17:39:51+00:00\",\"dateModified\":\"2019-05-15T00:40:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-07-noviembre-2016\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-07-noviembre-2016\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-07-noviembre-2016\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/sintesis_.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/sintesis_.jpg\",\"width\":958,\"height\":479},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-07-noviembre-2016\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00edntesis\",\"item\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S\u00edntesis Informativa de 07 de Noviembre de 2016\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/\",\"name\":\"CETYS\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00edntesis Informativa de 07 de Noviembre de 2016 - CETYS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-07-noviembre-2016\/","og_locale":"es_MX","og_type":"article","og_title":"S\u00edntesis Informativa de 07 de Noviembre de 2016 - CETYS","og_description":"Mexicali La Cr\u00f3nica Panteras y Borrgos van por el t\u00edtulo En el encuentro de Panteras ante Zorros, los del CETYS comenzaron imponi\u00e9ndose...","og_url":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-07-noviembre-2016\/","og_site_name":"CETYS","article_publisher":"https:\/\/www.facebook.com\/cetysuniversidadmxl\/","article_modified_time":"2019-05-15T00:40:41+00:00","og_image":[{"width":958,"height":479,"url":"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2016\/01\/sintesis_.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@cetysuni","twitter_misc":{"Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-07-noviembre-2016\/","url":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-07-noviembre-2016\/","name":"S\u00edntesis Informativa de 07 de Noviembre de 2016 - CETYS","isPartOf":{"@id":"https:\/\/www.cetys.mx\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-07-noviembre-2016\/#primaryimage"},"image":{"@id":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-07-noviembre-2016\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2016\/01\/sintesis_.jpg","datePublished":"2016-11-17T17:39:51+00:00","dateModified":"2019-05-15T00:40:41+00:00","breadcrumb":{"@id":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-07-noviembre-2016\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-07-noviembre-2016\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-07-noviembre-2016\/#primaryimage","url":"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2016\/01\/sintesis_.jpg","contentUrl":"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2016\/01\/sintesis_.jpg","width":958,"height":479},{"@type":"BreadcrumbList","@id":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-07-noviembre-2016\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cetys.mx\/noticias\/"},{"@type":"ListItem","position":2,"name":"S\u00edntesis","item":"https:\/\/www.cetys.mx\/noticias\/sintesis\/"},{"@type":"ListItem","position":3,"name":"S\u00edntesis Informativa de 07 de Noviembre de 2016"}]},{"@type":"WebSite","@id":"https:\/\/www.cetys.mx\/noticias\/#website","url":"https:\/\/www.cetys.mx\/noticias\/","name":"CETYS","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cetys.mx\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/sintesis\/67361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/sintesis"}],"about":[{"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/types\/sintesis"}],"author":[{"embeddable":true,"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/comments?post=67361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/media\/14504"}],"wp:attachment":[{"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/media?parent=67361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/categories?post=67361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}