{"id":118357,"date":"2018-09-13T12:00:19","date_gmt":"2018-09-13T19:00:19","guid":{"rendered":"http:\/\/www.cetys.mx\/noticias\/sintesis-informativa-de-13-de-septiembre-de-2018\/"},"modified":"2019-05-14T17:25:14","modified_gmt":"2019-05-15T00:25:14","slug":"sintesis-informativa-de-13-de-septiembre-de-2018","status":"publish","type":"sintesis","link":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-de-13-de-septiembre-de-2018\/","title":{"rendered":"S\u00edntesis Informativa de 13 de Septiembre  de 2018"},"content":{"rendered":"<p><!DOCTYPE html><\/p>\n<table width=\"800\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\" style=\"font-family:Tahoma, Geneva, sans-serif;\">\n<tr style=\" border:0px;\">\n<td width=\"103\" bgcolor=\"#ffdd00\">\n<table width=\"103\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\"><\/table>\n<\/td>\n<td width=\"406\" align=\"center\" style=\"background-image:url('https:\/\/www.cetys.mx\/noticias\/images\/head-sintesis.jpg'); text-align:center; background-size: cover;\">\n<h1>&nbsp;<\/h1>\n<h1 style=\"color:#FFF;font-size: 54px;\">S\u00edntesis Informativa<\/h1>\n<h3 style=\"color:#FFF;font-size: 27px;font-weight: normal;margin-top: 0px;padding-top: 0px;\">Sistema CETYS Universidad<\/h3>\n<p>&nbsp;<\/p>\n<\/td>\n<\/tr>\n<tr style=\" border:0px;\">\n<td bgcolor=\"#000\">&nbsp;<\/td>\n<td align=\"center\" valign=\"middle\" bgcolor=\"#000\" style=\"padding:18px; font-size:26px; text-align:center; color:#FFF;\"><img decoding=\"async\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/plugins\/sintesis-gen\/images\/logo-cetys-bn.png\" style=\"padding-right:30px; margin-right: 30px; border-right:2px solid #FFF;\" align=\"middle\">  13 de Septiembre  de 2018<\/td>\n<\/tr>\n<tr style=\" border:0px;\">\n<td bgcolor=\"#ffdd00\">&nbsp;<\/td>\n<td>&nbsp;<\/td>\n<\/tr>\n<tr style=\" border:0px;\">\n<td bgcolor=\"#ffdd00\">&nbsp;<\/td>\n<td style=\"padding:5px;\">\n<h1>Nacional<\/h1>\n<hr style=\"border-top: 2px solid #4c4747;\">\n<table width=\"100%\">\n<tr style=\"font-size:18px;\">\n<td width=\"60%\" align=\"left\" valign=\"top\" style=\"vertical-align: top;  border:0px; padding-bottom: 20px;\">\n                        <span><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-112900\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/05\/Campus-Milenio.png\" alt=\"\" width=\"140\" height=\"56\" \/> <\/span><br \/>\n                        <span style=\"font-size:20px;\"><b><a style=\"display: inline-block; padding-top:10px; color:#00a4e8;\" href=\"https:\/\/campusmilenio.mx\/index.php?option=com_k2&#038;view=item&#038;id=12600:cetys-presente-en-la-semana-nacional-del-emprendedor-2018&#038;Itemid=256\">Cetys presente en la Semana nacional del emprendedor 2018<\/a><\/b><\/span><br \/>\n                        <span><br \/>\n                            CETYS Universidad est\u00e1 participando en la Semana Nacional del Emprendedor en la CDMX.                         <\/span>\n                    <\/td>\n<td>\n                                        <img decoding=\"async\" style=\"width:100%;\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/Campus-milenio.jpg\">\n                    <\/td>\n<\/tr>\n<tr style=\"font-size:18px;\">\n<td width=\"60%\" align=\"left\" valign=\"top\" style=\"vertical-align: top;  border:0px; padding-bottom: 20px;\">\n                        <span><font style=\"font-size:18px; margin-left:15px;\">sociedad noticias<\/font> <\/span><br \/>\n                        <span style=\"font-size:20px;\"><b><a style=\"display: inline-block; padding-top:10px; color:#00a4e8;\" href=\"https:\/\/sociedadnoticias.com\/2018\/09\/12\/que-tipo-de-emprendedor-eres-cetys-universidad-cetysuni\/\">\u00bfQu\u00e9 tipo de emprendedor eres?: CETYS Universidad<\/a><\/b><\/span><br \/>\n                        <span><br \/>\n                            Un emprendedor, adem\u00e1s de conocer su producto, mercado, la competencia, tiene que desarrollar ciertas capacidades que le permitan tener ventaja sobre sus competidores y por esto, la importancia de conocer qu\u00e9 tipo de emprendedor eres.                        <\/span>\n                    <\/td>\n<td>\n                                        <img decoding=\"async\" style=\"width:100%;\" src=\"https:\/\/i2.wp.com\/sociedadnoticias.com\/wp-content\/uploads\/2018\/01\/fullsizeoutput_260.jpeg?fit=665%2C310&#038;ssl=1\">\n                    <\/td>\n<\/tr>\n<tr style=\"font-size:18px;\">\n<td width=\"60%\" align=\"left\" valign=\"top\" style=\"vertical-align: top;  border:0px; padding-bottom: 20px;\">\n                        <span><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-117968 alignleft\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/dineroenimagen18.jpg\" alt=\"\" width=\"193\" height=\"46\" \/> <\/span><br \/>\n                        <span style=\"font-size:20px;\"><b><a style=\"display: inline-block; padding-top:10px; color:#00a4e8;\" href=\"https:\/\/www.dineroenimagen.com\/el-contador\/el-contador\/103113\">El equipo Quantum, que est\u00e1 conformado por 11 personas estudiantes de diferentes ingenier\u00edas y licenciaturas<\/a><\/b><\/span><br \/>\n                        <span><br \/>\n                             El equipo de ingenieros Quantum, representado por Antonio Luna Mac\u00edas, que pertenece a CETYS Universidad, competir\u00e1 en el torneo gestionado por ARLISS Project en EU esta semana                        <\/span>\n                    <\/td>\n<td>\n                                        <img decoding=\"async\" style=\"width:100%;\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/elcontador.png\">\n                    <\/td>\n<\/tr>\n<tr style=\"font-size:18px;\">\n<td width=\"60%\" align=\"left\" valign=\"top\" style=\"vertical-align: top;  border:0px; padding-bottom: 20px;\">\n                        <span><font style=\"font-size:18px; margin-left:15px;\">24 Horas<\/font> <\/span><br \/>\n                        <span style=\"font-size:20px;\"><b><a style=\"display: inline-block; padding-top:10px; color:#00a4e8;\" href=\"https:\/\/www.24-horas.mx\/2018\/09\/05\/mexicanos-competiran-en-lanzamiento-de-cohetes-en-nevada\/\">Mexicanos competir\u00e1n en lanzamiento de cohetes en Nevada<\/a><\/b><\/span><br \/>\n                        <span><br \/>\n                            El equipo de CETYS ser\u00e1 el \u00fanico que competir\u00e1 en la categor\u00eda Comeback, la cual consiste en desarrollar un veh\u00edculo aut\u00f3nomo que ser\u00e1 lanzado a m\u00e1s de cuatro kil\u00f3metros de altura y liberar\u00e1 un paraca\u00eddas                        <\/span>\n                    <\/td>\n<td>\n                                        <img decoding=\"async\" style=\"width:100%;\" src=\"https:\/\/www.24-horas.mx\/wp-content\/uploads\/2018\/09\/Robots.jpg\">\n                    <\/td>\n<\/tr>\n<\/table>\n<h1>Mexicali<\/h1>\n<hr style=\"border-top: 2px solid #4c4747;\">\n<table width=\"100%\">\n<tr style=\"font-size:18px;\">\n<td width=\"60%\" align=\"left\" valign=\"top\" style=\"vertical-align: top;  border:0px; padding-bottom: 20px;\">\n                        <span><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-112903\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/05\/El-mexicano.png\" alt=\"\" width=\"140\" height=\"56\" \/> <\/span><br \/>\n                        <span style=\"font-size:20px;\"><b><a style=\"display: inline-block; padding-top:10px; color:#00a4e8;\" href=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/El-mexicano.jpg\">Circuito Nacional de Tenis Universitario<\/a><\/b><\/span><br \/>\n                        <span><br \/>\n                            Zorros de CETYS Universidad Campus Mexicali participar\u00e1n en la primera etapa del  Circuito Nacional de Tenis Universitario en Monterrey.                        <\/span>\n                    <\/td>\n<td>\n                                        <img decoding=\"async\" style=\"width:100%;\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/cetystenistas.jpg\">\n                    <\/td>\n<\/tr>\n<tr style=\"font-size:18px;\">\n<td width=\"60%\" align=\"left\" valign=\"top\" style=\"vertical-align: top;  border:0px; padding-bottom: 20px;\">\n                        <span><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-112903\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/05\/El-mexicano.png\" alt=\"\" width=\"140\" height=\"56\" \/> <\/span><br \/>\n                        <span style=\"font-size:20px;\"><b><a style=\"display: inline-block; padding-top:10px; color:#00a4e8;\" href=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/El-mexicano-2.jpg\">Destacan la generaci\u00f3n de empleo en glosa de SEDECO<\/a><\/b><\/span><br \/>\n                        <span><br \/>\n                            En la glosa de resultados de la Secretar\u00eda de Desarollo Econ\u00f3mico, se destaca la inversi\u00f3n a la educaci\u00f3n superior en CETYS Universidad con el Centro de Innovaci\u00f3n y manufactura aeroespacial de la instituci\u00f3n.                        <\/span>\n                    <\/td>\n<td>\n                                        <img decoding=\"async\" style=\"width:100%;\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/El-mexicano-2.jpg\">\n                    <\/td>\n<\/tr>\n<tr style=\"font-size:18px;\">\n<td width=\"60%\" align=\"left\" valign=\"top\" style=\"vertical-align: top;  border:0px; padding-bottom: 20px;\">\n                        <span><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/05\/monitor-economico.jpg\" alt=\"\" width=\"140\" height=\"56\" \/> <\/span><br \/>\n                        <span style=\"font-size:20px;\"><b><a style=\"display: inline-block; padding-top:10px; color:#00a4e8;\" href=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/monitor-econ\u00f3mico-2.jpg\">Impulsan CETYS y British Council crecimiento y desarrollo de mexicalenses<\/a><\/b><\/span><br \/>\n                        <span><br \/>\n                            CETYS Universidad Campus Mexicali y el British Council unen esfuerzos para brindar oportunidades de crecimiento y desarrollo profesional a los estudiantes del pa\u00eds, a trav\u00e9s de la implementaci\u00f3n del Sistema Inernacional de Prueba de Idioma Ingl\u00e9s (IELTS, por sus siglas en ingl\u00e9s).                        <\/span>\n                    <\/td>\n<td>\n                                        <img decoding=\"async\" style=\"width:100%;\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/3-3.jpg\">\n                    <\/td>\n<\/tr>\n<tr style=\"font-size:18px;\">\n<td width=\"60%\" align=\"left\" valign=\"top\" style=\"vertical-align: top;  border:0px; padding-bottom: 20px;\">\n                        <span><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/05\/uniradio-informa.jpg\" alt=\"\" width=\"140\" height=\"56\"\/> <\/span><br \/>\n                        <span style=\"font-size:20px;\"><b><a style=\"display: inline-block; padding-top:10px; color:#00a4e8;\" href=\"https:\/\/www.uniradioinforma.com\/noticias\/mexicali\/539536\/impulsan-crecimiento-y-desarrollo-profesional-de-los-mexicalenses.html\">Impulsan crecimiento y desarrollo profesional de los mexicalenses<\/a><\/b><\/span><br \/>\n                        <span><br \/>\n                            CETYS Universidad Campus Mexicali y el British Council unen esfuerzos para brindar oportunidades de crecimiento y desarrollo profesional a los estudiantes del pa\u00eds, a trav\u00e9s de la implementaci\u00f3n del Sistema Internacional de Prueba del Idioma Ingl\u00e9s (IELTS, por sus siglas en ingl\u00e9s).                        <\/span>\n                    <\/td>\n<td>\n                                        <img decoding=\"async\" style=\"width:100%;\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/2-3.jpg\">\n                    <\/td>\n<\/tr>\n<tr style=\"font-size:18px;\">\n<td width=\"60%\" align=\"left\" valign=\"top\" style=\"vertical-align: top;  border:0px; padding-bottom: 20px;\">\n                        <span><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-118342\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/Expreos-deportivo4.png\" alt=\"\" width=\"100\" height=\"34\" \/> <\/span><br \/>\n                        <span style=\"font-size:20px;\"><b><a style=\"display: inline-block; padding-top:10px; color:#00a4e8;\" href=\"https:\/\/www.expresodeportivo.com\/zorros-a-ultimo-compromiso-de-pretemporada\/\">Termina pretemporada de Zorros<\/a><\/b><\/span><br \/>\n                        <span><br \/>\n                            La Selecci\u00f3n de Zorros de CETYS Universidad conformada por los equipos de los Campus de Mexicali y Tijuana viaj\u00f3 el fin de semana a La Verne, en el condado de Los \u00c1ngeles en Estados Unidos para su \u00faltimo juego de pretemporada, enfrentando a Leopards de La Verne University en un juego que qued\u00f3 44-12 a favor de los locales.                        <\/span>\n                    <\/td>\n<td>\n                                        <img decoding=\"async\" style=\"width:100%;\" src=\"https:\/\/i1.wp.com\/www.expresodeportivo.com\/wp-content\/uploads\/2018\/09\/EDF_1058.jpg?fit=1200%2C807\">\n                    <\/td>\n<\/tr>\n<\/table>\n<h1>Tijuana<\/h1>\n<hr style=\"border-top: 2px solid #4c4747;\">\n<table width=\"100%\">\n<tr style=\"font-size:18px;\">\n<td width=\"60%\" align=\"left\" valign=\"top\" style=\"vertical-align: top;  border:0px; padding-bottom: 20px;\">\n                        <span><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-117957 alignleft\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/cetys_psnenlinea1.jpg\" alt=\"\" width=\"130\" height=\"26\" srcset=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/cetys_psnenlinea1.jpg 803w, https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/cetys_psnenlinea1-768x154.jpg 768w\" sizes=\"auto, (max-width: 130px) 100vw, 130px\" \/> <\/span><br \/>\n                        <span style=\"font-size:20px;\"><b><a style=\"display: inline-block; padding-top:10px; color:#00a4e8;\" href=\"https:\/\/psn.si\/robotica-arliss-cetys-fs\/2018\/09\/\">BC representa a M\u00e9xico en torneo internacional de rob\u00f3tica<\/a><\/b><\/span><br \/>\n                        <span><br \/>\n                             Estudiantes de ingenier\u00eda de Cetys Universidad pusieron manos a la obra. El reto, construir un robot aut\u00f3nomo que sea capaz de realizar una misi\u00f3n en un terreno inh\u00f3spito y que supere a sus contrincantes procedentes de distintos pa\u00edses, en el torneo que se lleva a cabo esta semana en Nevada, en Estados Unidos.                        <\/span>\n                    <\/td>\n<td>\n                                        <img decoding=\"async\" style=\"width:100%;\" src=\"https:\/\/psn.si\/wp-content\/uploads\/2018\/09\/BC-representa-a-M\u00e9xico-en-torneo-internacional-de-rob\u00f3tica.png\">\n                    <\/td>\n<\/tr>\n<tr style=\"font-size:18px;\">\n<td width=\"60%\" align=\"left\" valign=\"top\" style=\"vertical-align: top;  border:0px; padding-bottom: 20px;\">\n                        <span><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-118272 alignleft\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/cetys_soltijuana1.jpg\" alt=\"\" width=\"187\" height=\"35\" \/> <\/span><br \/>\n                        <span style=\"font-size:20px;\"><b><a style=\"display: inline-block; padding-top:10px; color:#00a4e8;\" href=\"https:\/\/www.elsoldetijuana.com.mx\/deportes\/cetys-a-defender-el-titulo-1991687.html\">CETYS, a defender el t\u00edtulo<\/a><\/b><\/span><br \/>\n                        <span><br \/>\n                            La quinteta de Cetys Universidad suma tres partidos hasta el momento, donde un grupo de jugadoras busca llenar 12 lugares para el arranque de campa\u00f1a.                        <\/span>\n                    <\/td>\n<td>\n                                        <img decoding=\"async\" style=\"width:100%;\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/Zorros.jpg\">\n                    <\/td>\n<\/tr>\n<tr style=\"font-size:18px;\">\n<td width=\"60%\" align=\"left\" valign=\"top\" style=\"vertical-align: top;  border:0px; padding-bottom: 20px;\">\n                        <span><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-118272 alignleft\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/cetys_soltijuana1.jpg\" alt=\"\" width=\"187\" height=\"35\" \/> <\/span><br \/>\n                        <span style=\"font-size:20px;\"><b><a style=\"display: inline-block; padding-top:10px; color:#00a4e8;\" href=\"https:\/\/www.elsoldetijuana.com.mx\/deportes\/se-preparan-cimarrones-para-enfrentar-a-zorros-1991677.html\">Se preparan Cimarrones para enfrentar a Zorros<\/a><\/b><\/span><br \/>\n                        <span><br \/>\n                                                    <\/span>\n                    <\/td>\n<td>\n                                        <img decoding=\"async\" style=\"width:100%;\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/Cimarrones.jpg\">\n                    <\/td>\n<\/tr>\n<tr style=\"font-size:18px;\">\n<td width=\"60%\" align=\"left\" valign=\"top\" style=\"vertical-align: top;  border:0px; padding-bottom: 20px;\">\n                        <span><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-118337 alignleft\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/pueblasports1.jpg\" alt=\"\" width=\"164\" height=\"54\" srcset=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/pueblasports1.jpg 604w, https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/pueblasports1-600x200.jpg 600w\" sizes=\"auto, (max-width: 164px) 100vw, 164px\" \/> <\/span><br \/>\n                        <span style=\"font-size:20px;\"><b><a style=\"display: inline-block; padding-top:10px; color:#00a4e8;\" href=\"https:\/\/www.puebla-sports.com\/blog\/myriam-lara-sigue-en-ascenso-jugar%C3%A1-de-manera-profesional-en-francia\">Myriam Lara sigue en ascenso, jugar\u00e1 de manera profesional en Francia<\/a><\/b><\/span><br \/>\n                        <span><br \/>\n                            Con 5 a\u00f1os jugando con el Cetys, la bajacaliforniana gan\u00f3 pr\u00e1cticamente todo, en el 2014 logr\u00f3 ser uno de los pilares importantes para que lograr\u00e1n el ascenso al m\u00e1ximo circuito de la Liga ABE, tras conseguir el campeonato de la Universiada Nacional tras vencer a las Linces de la UVM Lomas Verdes.                        <\/span>\n                    <\/td>\n<td>\n                                        <img decoding=\"async\" style=\"width:100%;\" src=\"https:\/\/static.wixstatic.com\/media\/fed170_9200f46a7f6f4477bb2e5c462c6832a7.png\">\n                    <\/td>\n<\/tr>\n<\/table>\n<h1>Ensenada<\/h1>\n<hr style=\"border-top: 2px solid #4c4747;\">\n<table width=\"100%\">\n<tr style=\"font-size:18px;\">\n<td width=\"60%\" align=\"left\" valign=\"top\" style=\"vertical-align: top;  border:0px; padding-bottom: 20px;\">\n                        <span><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/05\/radar-noticias.jpg\" alt=\"\" width=\"140\" height=\"56\" \/> <\/span><br \/>\n                        <span style=\"font-size:20px;\"><b><a style=\"display: inline-block; padding-top:10px; color:#00a4e8;\" href=\"https:\/\/radanoticias.info\/cetys-presente-en-la-semana-nacional-del-emprendedor\/\">CETYS PRESENTE EN LA SEMANA NACIONAL DEL EMPRENDEDOR<\/a><\/b><\/span><br \/>\n                        <span><br \/>\n                            Cetys Universidad participar\u00e1 en la Semana Nacional del Emprendedo con diversas actividades que buscar\u00e1n estrechar lazos de colaboraci\u00f3n con las instituciones participantes y brindar nuevas oportunidades para sus alumnos.                        <\/span>\n                    <\/td>\n<td>\n                                        <img decoding=\"async\" style=\"width:100%;\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/09\/Rada-1.jpeg\">\n                    <\/td>\n<\/tr>\n<tr style=\"font-size:18px;\">\n<td width=\"60%\" align=\"left\" valign=\"top\" style=\"vertical-align: top;  border:0px; padding-bottom: 20px;\">\n                        <span><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-112911\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/05\/ElVigiaLogo.jpg\" alt=\"\" width=\"140\" height=\"56\" \/> <\/span><br \/>\n                        <span style=\"font-size:20px;\"><b><a style=\"display: inline-block; padding-top:10px; color:#00a4e8;\" href=\"https:\/\/www.elvigia.net\/general\/2018\/9\/13\/dan-ponencia-sobre-educacion-integral-312327.html\">Dan ponencia sobre educaci\u00f3n integral<\/a><\/b><\/span><br \/>\n                        <span><br \/>\n                            Experto en temas como humanismo, \u00e9tica, familia y ciudadan\u00eda comparte conferencias sobre Responsabilidad Social con alumnos de Preparatoria, profesional y Posgrado de CETYS Universidad.<br \/>\n                        <\/span>\n                    <\/td>\n<td>\n                                        <img decoding=\"async\" style=\"width:100%;\" src=\"https:\/\/www.elvigia.net\/u\/fotografias\/m\/2018\/9\/12\/f960x0-384430_384448_31.jpg\">\n                    <\/td>\n<\/tr>\n<\/table>\n<p>&nbsp;<\/p>\n<\/td>\n<\/tr>\n<tr style=\" border:0px;\">\n<td bgcolor=\"#ffdd00\">&nbsp;<\/td>\n<td align=\"center\" bgcolor=\"#000000\" style=\"padding-left: 30px; color: #FFF;\">\n<p>&nbsp;<\/p>\n<h2><\/h2>\n<p>&nbsp;<\/p>\n<\/td>\n<\/tr>\n<tr style=\" border:0px;\">\n<td bgcolor=\"#ffdd00\">&nbsp;<\/td>\n<td style=\"padding-left:30px;\">\n<div style=\"text-align:center; font-size:20px;\">\n<h3>\n          Contactos:<\/h3>\n<\/p><\/div>\n<p>      <strong>COORDINACI&Oacute;N DE COMUNICACI&Oacute;N Y RELACIONES P&Uacute;BLICAS<\/strong><br \/>\n      <span style=\"font-size:14px;\"><\/p>\n<p>Campus Mexicali:<br \/>\n        <b>Mtra. Laura Odette Ram&iacute;rez Govea<\/b> | <img decoding=\"async\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/plugins\/sintesis-gen\/images\/icon-phone.png\"> +52 (686) 567-3782 | <img decoding=\"async\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/plugins\/sintesis-gen\/images\/icon-email.png\"> <a href=\"mailto:odette.ramirez@cetys.mx\">odette.ramirez@cetys.mx<\/a>\n      <\/p>\n<p>      <\/span><\/p>\n<p><span style=\"font-size:14px;\">Campus Tijuana:<br \/>\n        <b>Mtra. Angela N. Arroyo P&eacute;rez<\/b> | <img decoding=\"async\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/plugins\/sintesis-gen\/images\/icon-phone.png\"> +52 (664) 903-1853 | <img decoding=\"async\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/plugins\/sintesis-gen\/images\/icon-email.png\"> <a href=\"mailto:angela.arroyo@cetys.mx\">angela.arroyo@cetys.mx<\/a><br \/>\n      <\/span><\/p>\n<p><span style=\"font-size:14px;\">Campus Ensenada:<br \/>\n        <b>Lic. Cristina Nuza Ascolani<\/b> | <img decoding=\"async\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/plugins\/sintesis-gen\/images\/icon-phone.png\"> +52 (646) 222-2300 ext. 155 | <img decoding=\"async\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/plugins\/sintesis-gen\/images\/icon-email.png\"> <a href=\"mailto:cristina.nuza@cetys.mx\">cristina.nuza@cetys.mx<\/a><br \/>\n      <\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong>DIRECCI&Oacute;N DE COMUNICACI&Oacute;N INSTITUCIONAL<\/strong><br \/>\n        <span style=\"font-size:14px;\"><b>Mtro. Francisco Reyes Cervantes<\/b> | <img decoding=\"async\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/plugins\/sintesis-gen\/images\/icon-phone.png\"> +52 (664) 903-1800 ext. 340| <img decoding=\"async\" src=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/plugins\/sintesis-gen\/images\/icon-email.png\"> <a href=\"mailto:francisco.reyes@cetys.mx\">francisco.reyes@cetys.mx<\/a><br \/>\n      <\/span><\/p>\n<p>&nbsp;<\/p>\n<\/td>\n<\/tr>\n<tr style=\" border:0px;\">\n<td bgcolor=\"#ffdd00\">&nbsp;<\/td>\n<td>&nbsp;<\/td>\n<\/tr>\n<\/table>\n<style>\n.article-content{\n  padding: 0px;\n}\n.article-content table {\n    width: initial !important;\n}<\/p>\n<\/style>\n<p><\/center><br \/>\n<\/body><br \/>\n<\/html><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; S\u00edntesis Informativa Sistema CETYS Universidad &nbsp; &nbsp; 13 de Septiembre de 2018 &nbsp; &nbsp; &nbsp; Nacional Cetys presente en la Semana&#8230;<\/p>\n","protected":false},"author":26,"featured_media":109042,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","categories":[130],"class_list":["post-118357","sintesis","type-sintesis","status-publish","has-post-thumbnail","hentry","category-sintesis-informativa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00edntesis Informativa de 13 de Septiembre de 2018 - CETYS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-de-13-de-septiembre-de-2018\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00edntesis Informativa de 13 de Septiembre de 2018 - CETYS\" \/>\n<meta property=\"og:description\" content=\"&nbsp; S\u00edntesis Informativa Sistema CETYS Universidad &nbsp; &nbsp; 13 de Septiembre de 2018 &nbsp; &nbsp; &nbsp; Nacional Cetys presente en la Semana...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-de-13-de-septiembre-de-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"CETYS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cetysuniversidadmxl\/\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-15T00:25:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/02\/sintesis_2018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"958\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cetysuni\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-de-13-de-septiembre-de-2018\\\/\",\"url\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-de-13-de-septiembre-de-2018\\\/\",\"name\":\"S\u00edntesis Informativa de 13 de Septiembre de 2018 - CETYS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-de-13-de-septiembre-de-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-de-13-de-septiembre-de-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/sintesis_2018.jpg\",\"datePublished\":\"2018-09-13T19:00:19+00:00\",\"dateModified\":\"2019-05-15T00:25:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-de-13-de-septiembre-de-2018\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-de-13-de-septiembre-de-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-de-13-de-septiembre-de-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/sintesis_2018.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/sintesis_2018.jpg\",\"width\":958,\"height\":479},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/sintesis-informativa-de-13-de-septiembre-de-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00edntesis\",\"item\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/sintesis\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"S\u00edntesis Informativa de 13 de Septiembre de 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/\",\"name\":\"CETYS\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00edntesis Informativa de 13 de Septiembre de 2018 - CETYS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-de-13-de-septiembre-de-2018\/","og_locale":"es_MX","og_type":"article","og_title":"S\u00edntesis Informativa de 13 de Septiembre de 2018 - CETYS","og_description":"&nbsp; S\u00edntesis Informativa Sistema CETYS Universidad &nbsp; &nbsp; 13 de Septiembre de 2018 &nbsp; &nbsp; &nbsp; Nacional Cetys presente en la Semana...","og_url":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-de-13-de-septiembre-de-2018\/","og_site_name":"CETYS","article_publisher":"https:\/\/www.facebook.com\/cetysuniversidadmxl\/","article_modified_time":"2019-05-15T00:25:14+00:00","og_image":[{"width":958,"height":479,"url":"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/02\/sintesis_2018.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@cetysuni","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-de-13-de-septiembre-de-2018\/","url":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-de-13-de-septiembre-de-2018\/","name":"S\u00edntesis Informativa de 13 de Septiembre de 2018 - CETYS","isPartOf":{"@id":"https:\/\/www.cetys.mx\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-de-13-de-septiembre-de-2018\/#primaryimage"},"image":{"@id":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-de-13-de-septiembre-de-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/02\/sintesis_2018.jpg","datePublished":"2018-09-13T19:00:19+00:00","dateModified":"2019-05-15T00:25:14+00:00","breadcrumb":{"@id":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-de-13-de-septiembre-de-2018\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-de-13-de-septiembre-de-2018\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-de-13-de-septiembre-de-2018\/#primaryimage","url":"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/02\/sintesis_2018.jpg","contentUrl":"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2018\/02\/sintesis_2018.jpg","width":958,"height":479},{"@type":"BreadcrumbList","@id":"https:\/\/www.cetys.mx\/noticias\/sintesis\/sintesis-informativa-de-13-de-septiembre-de-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cetys.mx\/noticias\/"},{"@type":"ListItem","position":2,"name":"S\u00edntesis","item":"https:\/\/www.cetys.mx\/noticias\/sintesis\/"},{"@type":"ListItem","position":3,"name":"S\u00edntesis Informativa de 13 de Septiembre de 2018"}]},{"@type":"WebSite","@id":"https:\/\/www.cetys.mx\/noticias\/#website","url":"https:\/\/www.cetys.mx\/noticias\/","name":"CETYS","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cetys.mx\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/sintesis\/118357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/sintesis"}],"about":[{"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/types\/sintesis"}],"author":[{"embeddable":true,"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/comments?post=118357"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/media\/109042"}],"wp:attachment":[{"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/media?parent=118357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/categories?post=118357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}