{"id":175777,"date":"2023-09-08T12:33:21","date_gmt":"2023-09-08T19:33:21","guid":{"rendered":"https:\/\/www.cetys.mx\/noticias\/?p=175777"},"modified":"2023-09-12T12:53:56","modified_gmt":"2023-09-12T19:53:56","slug":"antecedentes-penales-derecho","status":"publish","type":"post","link":"https:\/\/www.cetys.mx\/noticias\/antecedentes-penales-derecho\/","title":{"rendered":"Derecho al trabajo y antecedentes penales: Entre la reinserci\u00f3n y la discriminaci\u00f3n"},"content":{"rendered":"<p style=\"text-align: center;\"><b><i>La carta de no antecedentes penales sigue figurando entre los requisitos para ocupar cargos de car\u00e1cter p\u00fablico y privado, pese a que hacerlo es un acto discriminatorio y vulnera los derechos humanos de los aspirantes, explica Experto CETYS<\/i><\/b><\/p>\n<p><span style=\"font-weight: 400;\">La Reforma Constitucional del a\u00f1o 2008; hace 15 a\u00f1os, vino a regular una serie de cambios significativos en el Sistema de Justicia Penal y el Sistema Penitenciario mexicano. Entre dichos cambios se encuentra un tema que contin\u00faa generando dudas entre la poblaci\u00f3n: La carta de no antecedentes penales, un documento que figura entre los requisitos de ingreso para los aspirantes a ocupar un cargo tanto de car\u00e1cter p\u00fablico, como en la iniciativa privada.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La Suprema Corte de Justicia de la Naci\u00f3n se pronunci\u00f3 al respecto, declarando inconstitucional el hecho de requerir la carta de no antecedentes penales para contratar, pues hacerlo atenta contra el esp\u00edritu de la Reforma Constitucional, espec\u00edficamente del art\u00edculo 18, donde se establece que el Sistema Penitenciario se organizar\u00e1 sobre la base del respeto a los derechos humanos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cEntonces, tal exigencia a los aspirantes a ocupar un empleo vulnera sus derechos de igualdad ante la ley, teniendo en cuenta los derechos inherentes de todo ser humano consagrados en nuestra Carta Magna\u201d, se\u00f1al\u00f3 el Dr. Cristian Colosio Lule, docente de la Escuela de Derecho de CETYS Universidad Campus Mexicali.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A\u00f1adi\u00f3 que, en la pr\u00e1ctica, una persona que en alg\u00fan momento de su vida tuvo problemas con la justicia por haber cometido alg\u00fan delito y que, derivado de ello cumpli\u00f3 una sentencia de condena, cuando sale libre tiene pocas alternativas para reinsertarse en su comunidad, disminuyendo sus probabilidades de lograrlo.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cAlgunos de los principales problemas a los que se tiene que enfrentar una persona que en alg\u00fan momento de su vida fue merecedor de un castigo o sanci\u00f3n penal, son el quebrantamiento de la familia por los a\u00f1os que estuvo preso, la disfunci\u00f3n familiar, el poco avance en el derecho y acceso a lograr grados acad\u00e9micos y, sobre todo, la discriminaci\u00f3n que se realiza en su persona al ser juzgado por los dem\u00e1s\u201d.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En un entorno cambiante, en el que las normas punitivas son constantemente modificadas como un medio para regular el comportamiento de la comunidad, y donde se apuesta a que una persona que enfrenta un proceso en su contra pueda hacerlo en libertad (en la mayor\u00eda de los casos), respetando el principio de inocencia, es la propia sociedad la que una vez que se dictan condenas a quienes efectivamente resultan responsables de sus acusaciones, expone a estas personas a se\u00f1alamientos y al escarnio p\u00fablico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cAl recibir una persona un castigo o pena por la conducta delictiva realizada y haber permanecido en prisi\u00f3n durante determinado tiempo, se debe de entender que dicha ya ha cumplido con el castigo, y que en ese sentido, en igualdad de condiciones, debe tener acceso a todos los derechos consagrados en nuestra Carta Magna, uno de esos derechos sin duda es el poder desempe\u00f1arse en un trabajo o profesi\u00f3n\u201d, expres\u00f3 el especialista.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cuando ocurre lo contrario y a la persona en cuesti\u00f3n se le discrimina y se le obstaculiza el derecho de obtener un empleo por contar con antecedentes penales, el afectado puede solicitar a la autoridad el amparo de la justicia federal para que le hagan valer sus derechos constitucionales de no ser discriminado y tener acceso a las mismas oportunidades que cualquier otro ciudadano que no haya sido condenado por la comisi\u00f3n de alg\u00fan delito.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">\u201cD\u00eda con d\u00eda nuestras leyes se est\u00e1n modificando, permiten mayor apertura a la aplicaci\u00f3n de lineamientos internacionales, que nuestra constituci\u00f3n est\u00e1 para que se respete; pero por otro lado tambi\u00e9n prevalecen muchas personas con mentalidad inquisitiva y no creen en la reinserci\u00f3n, piensan que una persona que ha cometido alguna conducta delictiva y que ha sido merecedor a un castigo jam\u00e1s lograr\u00e1 dicha reinserci\u00f3n, y que por lo tanto, debe ser discriminado ante lo dem\u00e1s, lo cual desde luego es un total error\u201d, concluy\u00f3 el docente. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La carta de no antecedentes penales sigue figurando entre los requisitos para ocupar cargos de car\u00e1cter p\u00fablico y privado, pese a que&#8230;<\/p>\n","protected":false},"author":20,"featured_media":175776,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[133,4579,313],"tags":[5023,1622,247,6566],"class_list":["post-175777","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-campus-mexicali","category-expertos-cetys","category-vocetys-2","tag-expertoscetys","tag-campusmexicali","tag-derecho","tag-vocetys-2023-09-12"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Derecho al trabajo y antecedentes penales: Entre la reinserci\u00f3n y la discriminaci\u00f3n - CETYS<\/title>\n<meta name=\"description\" content=\"Articulo sobre Derecho al trabajo y antecedentes penales: Entre la reinserci\u00f3n y la discriminaci\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cetys.mx\/noticias\/antecedentes-penales-derecho\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Derecho al trabajo y antecedentes penales: Entre la reinserci\u00f3n y la discriminaci\u00f3n - CETYS\" \/>\n<meta property=\"og:description\" content=\"Articulo sobre Derecho al trabajo y antecedentes penales: Entre la reinserci\u00f3n y la discriminaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cetys.mx\/noticias\/antecedentes-penales-derecho\/\" \/>\n<meta property=\"og:site_name\" content=\"CETYS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cetysuniversidadmxl\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-08T19:33:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-12T19:53:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2023\/09\/Antecedentes-penales.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"958\" \/>\n\t<meta property=\"og:image:height\" content=\"637\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Campus Mexicali\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cetysuni\" \/>\n<meta name=\"twitter:site\" content=\"@cetysuni\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Campus Mexicali\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/antecedentes-penales-derecho\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/antecedentes-penales-derecho\\\/\"},\"author\":{\"name\":\"Campus Mexicali\",\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/#\\\/schema\\\/person\\\/79a95c4ac185f3705cf1b9c9340a5f70\"},\"headline\":\"Derecho al trabajo y antecedentes penales: Entre la reinserci\u00f3n y la discriminaci\u00f3n\",\"datePublished\":\"2023-09-08T19:33:21+00:00\",\"dateModified\":\"2023-09-12T19:53:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/antecedentes-penales-derecho\\\/\"},\"wordCount\":713,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/antecedentes-penales-derecho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Antecedentes-penales.jpg\",\"keywords\":[\"#ExpertosCETYS\",\"campusmexicali\",\"Derecho\",\"vocetys-2023-09-12\"],\"articleSection\":[\"Campus Mexicali\",\"Expertos CETYS\",\"VoCETYS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/antecedentes-penales-derecho\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/antecedentes-penales-derecho\\\/\",\"url\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/antecedentes-penales-derecho\\\/\",\"name\":\"Derecho al trabajo y antecedentes penales: Entre la reinserci\u00f3n y la discriminaci\u00f3n - CETYS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/antecedentes-penales-derecho\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/antecedentes-penales-derecho\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Antecedentes-penales.jpg\",\"datePublished\":\"2023-09-08T19:33:21+00:00\",\"dateModified\":\"2023-09-12T19:53:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/#\\\/schema\\\/person\\\/79a95c4ac185f3705cf1b9c9340a5f70\"},\"description\":\"Articulo sobre Derecho al trabajo y antecedentes penales: Entre la reinserci\u00f3n y la discriminaci\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/antecedentes-penales-derecho\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/antecedentes-penales-derecho\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/antecedentes-penales-derecho\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Antecedentes-penales.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Antecedentes-penales.jpg\",\"width\":958,\"height\":637},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/antecedentes-penales-derecho\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Derecho al trabajo y antecedentes penales: Entre la reinserci\u00f3n y la discriminaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/\",\"name\":\"CETYS\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/#\\\/schema\\\/person\\\/79a95c4ac185f3705cf1b9c9340a5f70\",\"name\":\"Campus Mexicali\",\"url\":\"https:\\\/\\\/www.cetys.mx\\\/noticias\\\/author\\\/campusmexicali\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Derecho al trabajo y antecedentes penales: Entre la reinserci\u00f3n y la discriminaci\u00f3n - CETYS","description":"Articulo sobre Derecho al trabajo y antecedentes penales: Entre la reinserci\u00f3n y la discriminaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cetys.mx\/noticias\/antecedentes-penales-derecho\/","og_locale":"es_MX","og_type":"article","og_title":"Derecho al trabajo y antecedentes penales: Entre la reinserci\u00f3n y la discriminaci\u00f3n - CETYS","og_description":"Articulo sobre Derecho al trabajo y antecedentes penales: Entre la reinserci\u00f3n y la discriminaci\u00f3n","og_url":"https:\/\/www.cetys.mx\/noticias\/antecedentes-penales-derecho\/","og_site_name":"CETYS","article_publisher":"https:\/\/www.facebook.com\/cetysuniversidadmxl\/","article_published_time":"2023-09-08T19:33:21+00:00","article_modified_time":"2023-09-12T19:53:56+00:00","og_image":[{"width":958,"height":637,"url":"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2023\/09\/Antecedentes-penales.jpg","type":"image\/jpeg"}],"author":"Campus Mexicali","twitter_card":"summary_large_image","twitter_creator":"@cetysuni","twitter_site":"@cetysuni","twitter_misc":{"Escrito por":"Campus Mexicali","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cetys.mx\/noticias\/antecedentes-penales-derecho\/#article","isPartOf":{"@id":"https:\/\/www.cetys.mx\/noticias\/antecedentes-penales-derecho\/"},"author":{"name":"Campus Mexicali","@id":"https:\/\/www.cetys.mx\/noticias\/#\/schema\/person\/79a95c4ac185f3705cf1b9c9340a5f70"},"headline":"Derecho al trabajo y antecedentes penales: Entre la reinserci\u00f3n y la discriminaci\u00f3n","datePublished":"2023-09-08T19:33:21+00:00","dateModified":"2023-09-12T19:53:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cetys.mx\/noticias\/antecedentes-penales-derecho\/"},"wordCount":713,"commentCount":0,"image":{"@id":"https:\/\/www.cetys.mx\/noticias\/antecedentes-penales-derecho\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2023\/09\/Antecedentes-penales.jpg","keywords":["#ExpertosCETYS","campusmexicali","Derecho","vocetys-2023-09-12"],"articleSection":["Campus Mexicali","Expertos CETYS","VoCETYS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cetys.mx\/noticias\/antecedentes-penales-derecho\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cetys.mx\/noticias\/antecedentes-penales-derecho\/","url":"https:\/\/www.cetys.mx\/noticias\/antecedentes-penales-derecho\/","name":"Derecho al trabajo y antecedentes penales: Entre la reinserci\u00f3n y la discriminaci\u00f3n - CETYS","isPartOf":{"@id":"https:\/\/www.cetys.mx\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cetys.mx\/noticias\/antecedentes-penales-derecho\/#primaryimage"},"image":{"@id":"https:\/\/www.cetys.mx\/noticias\/antecedentes-penales-derecho\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2023\/09\/Antecedentes-penales.jpg","datePublished":"2023-09-08T19:33:21+00:00","dateModified":"2023-09-12T19:53:56+00:00","author":{"@id":"https:\/\/www.cetys.mx\/noticias\/#\/schema\/person\/79a95c4ac185f3705cf1b9c9340a5f70"},"description":"Articulo sobre Derecho al trabajo y antecedentes penales: Entre la reinserci\u00f3n y la discriminaci\u00f3n","breadcrumb":{"@id":"https:\/\/www.cetys.mx\/noticias\/antecedentes-penales-derecho\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cetys.mx\/noticias\/antecedentes-penales-derecho\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.cetys.mx\/noticias\/antecedentes-penales-derecho\/#primaryimage","url":"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2023\/09\/Antecedentes-penales.jpg","contentUrl":"https:\/\/www.cetys.mx\/noticias\/wp-content\/uploads\/2023\/09\/Antecedentes-penales.jpg","width":958,"height":637},{"@type":"BreadcrumbList","@id":"https:\/\/www.cetys.mx\/noticias\/antecedentes-penales-derecho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.cetys.mx\/noticias\/"},{"@type":"ListItem","position":2,"name":"Derecho al trabajo y antecedentes penales: Entre la reinserci\u00f3n y la discriminaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.cetys.mx\/noticias\/#website","url":"https:\/\/www.cetys.mx\/noticias\/","name":"CETYS","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cetys.mx\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cetys.mx\/noticias\/#\/schema\/person\/79a95c4ac185f3705cf1b9c9340a5f70","name":"Campus Mexicali","url":"https:\/\/www.cetys.mx\/noticias\/author\/campusmexicali\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/posts\/175777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/comments?post=175777"}],"version-history":[{"count":1,"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/posts\/175777\/revisions"}],"predecessor-version":[{"id":175778,"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/posts\/175777\/revisions\/175778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/media\/175776"}],"wp:attachment":[{"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/media?parent=175777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/categories?post=175777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cetys.mx\/noticias\/wp-json\/wp\/v2\/tags?post=175777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}