{"id":3467,"date":"2020-12-22T12:04:27","date_gmt":"2020-12-22T20:04:27","guid":{"rendered":"https:\/\/www.cetys.mx\/educon\/?p=3467"},"modified":"2021-01-27T10:18:44","modified_gmt":"2021-01-27T18:18:44","slug":"conceptos-basicos-de-seguridad-industrial","status":"publish","type":"post","link":"https:\/\/www.cetys.mx\/educon\/conceptos-basicos-de-seguridad-industrial\/","title":{"rendered":"Conceptos b\u00e1sicos de seguridad industrial"},"content":{"rendered":"\r\n<p class=\"wp-block-paragraph\">Se denomina seguridad industrial al conjunto de normas obligatorias establecidas para evitar o minimizar, tanto los riesgos que puedan efectuarse en los \u00e1mbitos industriales, como los perjuicios derivados de la actividad industrial e incluso las enfermedades ocupacionales. Dado que por las maquinarias y las herramientas que se utilizan son \u00e1reas propensas al peligro, mediante la prevenci\u00f3n se busca evitar el da\u00f1o a las personas, a los bienes y reducir el impacto en el medio ambiente. La seguridad industrial debe ser cumplida obligatoriamente en todas las empresas y la principal finalidad del cumplimiento de estas disposiciones es brindar seguridad al trabajador dentro del \u00e1mbito laboral.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Las empresas o industrias tienen la responsabilidad de generar condiciones de trabajo que garanticen protecci\u00f3n y seguridad a sus trabajadores; para ello deben implementar una serie de normas y condiciones que reduzcan el riesgo de sufrir un accidente laboral.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><strong>Medidas de seguridad industrial indispensables en toda empresa:<\/strong><\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\"><li>Abastecimiento de protecci\u00f3n personal: todo trabajador debe ser provisto de indumentaria apta e indicada para realizar sus actividades laborales de forma segura. De ser necesario debe proveerse un equipo de seguridad, como por ejemplo arn\u00e9s, mascaras, guantes, gafas de seguridad y todo aquello que ayude a disminuir el riesgo de padecer accidentes laborales.<\/li><li>Garantizar un \u00e1rea de trabajo segura: un espacio de trabajo mal dise\u00f1ado puede ser un gran peligro para los trabajadores. Es imprescindible que los centros de trabajo presenten salidas de emergencia accesibles, zonas de paso amplias y libres de obst\u00e1culos para evitar embotellamiento, salidas debidamente se\u00f1alizadas, poseer un plan para casos de emergencia y tener un sistema contra incendios; el \u00e1rea debe contar con una iluminaci\u00f3n adecuada, los pisos no deben ser irregulares ni resbaladizos, y las maquinarias deben tener una distancia de separaci\u00f3n suficiente para que los trabajadores puedan realizar sus tareas c\u00f3modamente.<\/li><li>Brindar capacitaci\u00f3n: es importante que los trabajadores reciban una formaci\u00f3n adecuada, en la cual puedan adquirir los conocimientos necesarios, para desempe\u00f1ar su labor de forma segura y competente; as\u00ed mismo, deben ser capacitados para utilizar los elementos de seguridad de forma correcta.<\/li><\/ul>\r\n\r\n\r\n\r\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Al invertir en seguridad industrial y reducir los riesgos laborales, las empresas disminuyen los costos de operaci\u00f3n y obtienen mas ganancias, al mismo tiempo que protegen a sus empleados, maquinarias y recursos, dado que:<\/p>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\"><li>Al no presentarse accidentes se reduce considerablemente el absentismo.<\/li><li>La jornada laboral no se ve interrumpida por accidentes o imprevistos.<\/li><li>Se crea un mejor ambiente laboral donde los trabajadores realizan sus tareas m\u00e1s a gusto, mejorando la productividad y competitividad.<\/li><li>Se reducen los costos que generan los da\u00f1os a los equipos, edificios y se evitan los pagos de indemnizaci\u00f3n.<\/li><\/ul>\r\n\r\n\r\n\r\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Aplicando las normas de seguridad industrial, a la vez que se protege la vida e integridad del trabajador, se obtienen grandes ahorros financieros.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Si est\u00e1s interesado en aprender los procesos t\u00e9cnicos, administrativos y legales de la seguridad e higiene industrial y su correcta aplicaci\u00f3n en las empresas, en <a href=\"https:\/\/www.cetys.mx\/educon\/programas-de-estudio-mexicali\/\">CETYS Educaci\u00f3n Continua<\/a> adquirir\u00e1s los conocimientos necesarios a trav\u00e9s de nuestro <a href=\"https:\/\/www.cetys.mx\/educon\/programas\/diplomado-en-seguridad-higiene-y-medio-ambiente\/\">Diplomado en Seguridad, Higiene y Medio Ambiente<\/a> para que puedas desarrollarte y crecer profesionalmente. <a href=\"https:\/\/www.cetys.mx\/educon\/w-files\/\">acta de matrimonio<\/a><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Las empresas o industrias tienen la responsabilidad de generar condiciones de trabajo que garanticen protecci\u00f3n y seguridad a sus trabajadores; para ello deben implementar una serie de normas y condiciones que reduzcan el riesgo de sufrir un accidente laboral.<\/p>\n","protected":false},"author":1,"featured_media":3468,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,75],"tags":[34],"categoria_programa":[52],"class_list":["post-3467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos","category-seguridad-industrial","tag-mexicali","categoria_programa-salud-y-calidad-de-vida"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conceptos b\u00e1sicos de seguridad industrial - CETYS Educaci\u00f3n Continua<\/title>\n<meta name=\"description\" content=\"Las empresas o industrias tienen la responsabilidad de generar condiciones de trabajo que garanticen protecci\u00f3n y seguridad a sus trabajadores; para ello deben implementar una serie de normas y condiciones que reduzcan el riesgo de sufrir un accidente laboral.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cetys.mx\/educon\/conceptos-basicos-de-seguridad-industrial\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conceptos b\u00e1sicos de seguridad industrial - CETYS Educaci\u00f3n Continua\" \/>\n<meta property=\"og:description\" content=\"Las empresas o industrias tienen la responsabilidad de generar condiciones de trabajo que garanticen protecci\u00f3n y seguridad a sus trabajadores; para ello deben implementar una serie de normas y condiciones que reduzcan el riesgo de sufrir un accidente laboral.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cetys.mx\/educon\/conceptos-basicos-de-seguridad-industrial\/\" \/>\n<meta property=\"og:site_name\" content=\"CETYS Educaci\u00f3n Continua\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-22T20:04:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-27T18:18:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cetys.mx\/educon\/wp-content\/uploads\/2020\/12\/young-male-handyman-with-safety-earphones-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CETYS Educaci\u00f3n Continua\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"CETYS Educaci\u00f3n Continua\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cetys.mx\/educon\/conceptos-basicos-de-seguridad-industrial\/\",\"url\":\"https:\/\/www.cetys.mx\/educon\/conceptos-basicos-de-seguridad-industrial\/\",\"name\":\"Conceptos b\u00e1sicos de seguridad industrial - CETYS Educaci\u00f3n Continua\",\"isPartOf\":{\"@id\":\"https:\/\/www.cetys.mx\/educon\/#website\"},\"datePublished\":\"2020-12-22T20:04:27+00:00\",\"dateModified\":\"2021-01-27T18:18:44+00:00\",\"author\":{\"@id\":\"https:\/\/www.cetys.mx\/educon\/#\/schema\/person\/bab052cbfde2c12e18f3cc3fd3fa1f6b\"},\"description\":\"Las empresas o industrias tienen la responsabilidad de generar condiciones de trabajo que garanticen protecci\u00f3n y seguridad a sus trabajadores; para ello deben implementar una serie de normas y condiciones que reduzcan el riesgo de sufrir un accidente laboral.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cetys.mx\/educon\/conceptos-basicos-de-seguridad-industrial\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cetys.mx\/educon\/conceptos-basicos-de-seguridad-industrial\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cetys.mx\/educon\/conceptos-basicos-de-seguridad-industrial\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.cetys.mx\/educon\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conceptos b\u00e1sicos de seguridad industrial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cetys.mx\/educon\/#website\",\"url\":\"https:\/\/www.cetys.mx\/educon\/\",\"name\":\"CETYS Educaci\u00f3n Continua\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cetys.mx\/educon\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.cetys.mx\/educon\/#\/schema\/person\/bab052cbfde2c12e18f3cc3fd3fa1f6b\",\"name\":\"CETYS Educaci\u00f3n Continua\",\"sameAs\":[\"https:\/\/www.cetys.mx\/educon\"],\"url\":\"https:\/\/www.cetys.mx\/educon\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conceptos b\u00e1sicos de seguridad industrial - CETYS Educaci\u00f3n Continua","description":"Las empresas o industrias tienen la responsabilidad de generar condiciones de trabajo que garanticen protecci\u00f3n y seguridad a sus trabajadores; para ello deben implementar una serie de normas y condiciones que reduzcan el riesgo de sufrir un accidente laboral.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cetys.mx\/educon\/conceptos-basicos-de-seguridad-industrial\/","og_locale":"es_MX","og_type":"article","og_title":"Conceptos b\u00e1sicos de seguridad industrial - CETYS Educaci\u00f3n Continua","og_description":"Las empresas o industrias tienen la responsabilidad de generar condiciones de trabajo que garanticen protecci\u00f3n y seguridad a sus trabajadores; para ello deben implementar una serie de normas y condiciones que reduzcan el riesgo de sufrir un accidente laboral.","og_url":"https:\/\/www.cetys.mx\/educon\/conceptos-basicos-de-seguridad-industrial\/","og_site_name":"CETYS Educaci\u00f3n Continua","article_published_time":"2020-12-22T20:04:27+00:00","article_modified_time":"2021-01-27T18:18:44+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/www.cetys.mx\/educon\/wp-content\/uploads\/2020\/12\/young-male-handyman-with-safety-earphones-scaled.jpg","type":"image\/jpeg"}],"author":"CETYS Educaci\u00f3n Continua","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"CETYS Educaci\u00f3n Continua","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cetys.mx\/educon\/conceptos-basicos-de-seguridad-industrial\/","url":"https:\/\/www.cetys.mx\/educon\/conceptos-basicos-de-seguridad-industrial\/","name":"Conceptos b\u00e1sicos de seguridad industrial - CETYS Educaci\u00f3n Continua","isPartOf":{"@id":"https:\/\/www.cetys.mx\/educon\/#website"},"datePublished":"2020-12-22T20:04:27+00:00","dateModified":"2021-01-27T18:18:44+00:00","author":{"@id":"https:\/\/www.cetys.mx\/educon\/#\/schema\/person\/bab052cbfde2c12e18f3cc3fd3fa1f6b"},"description":"Las empresas o industrias tienen la responsabilidad de generar condiciones de trabajo que garanticen protecci\u00f3n y seguridad a sus trabajadores; para ello deben implementar una serie de normas y condiciones que reduzcan el riesgo de sufrir un accidente laboral.","breadcrumb":{"@id":"https:\/\/www.cetys.mx\/educon\/conceptos-basicos-de-seguridad-industrial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cetys.mx\/educon\/conceptos-basicos-de-seguridad-industrial\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.cetys.mx\/educon\/conceptos-basicos-de-seguridad-industrial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cetys.mx\/educon\/"},{"@type":"ListItem","position":2,"name":"Conceptos b\u00e1sicos de seguridad industrial"}]},{"@type":"WebSite","@id":"https:\/\/www.cetys.mx\/educon\/#website","url":"https:\/\/www.cetys.mx\/educon\/","name":"CETYS Educaci\u00f3n Continua","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cetys.mx\/educon\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.cetys.mx\/educon\/#\/schema\/person\/bab052cbfde2c12e18f3cc3fd3fa1f6b","name":"CETYS Educaci\u00f3n Continua","sameAs":["https:\/\/www.cetys.mx\/educon"],"url":"https:\/\/www.cetys.mx\/educon\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.cetys.mx\/educon\/wp-json\/wp\/v2\/posts\/3467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cetys.mx\/educon\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cetys.mx\/educon\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cetys.mx\/educon\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cetys.mx\/educon\/wp-json\/wp\/v2\/comments?post=3467"}],"version-history":[{"count":3,"href":"https:\/\/www.cetys.mx\/educon\/wp-json\/wp\/v2\/posts\/3467\/revisions"}],"predecessor-version":[{"id":3607,"href":"https:\/\/www.cetys.mx\/educon\/wp-json\/wp\/v2\/posts\/3467\/revisions\/3607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cetys.mx\/educon\/wp-json\/wp\/v2\/media\/3468"}],"wp:attachment":[{"href":"https:\/\/www.cetys.mx\/educon\/wp-json\/wp\/v2\/media?parent=3467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cetys.mx\/educon\/wp-json\/wp\/v2\/categories?post=3467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cetys.mx\/educon\/wp-json\/wp\/v2\/tags?post=3467"},{"taxonomy":"categoria_programa","embeddable":true,"href":"https:\/\/www.cetys.mx\/educon\/wp-json\/wp\/v2\/categoria_programa?post=3467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}